{"id":10015,"date":"2024-10-23T13:55:00","date_gmt":"2024-10-23T13:55:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=10015"},"modified":"2024-10-24T04:17:50","modified_gmt":"2024-10-24T04:17:50","slug":"ricardo-gallardo-lleva-mas-apoyo-a-las-familias-de-la-capital-con-paquetes-alimentarios","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2024\/10\/23\/ricardo-gallardo-lleva-mas-apoyo-a-las-familias-de-la-capital-con-paquetes-alimentarios\/","title":{"rendered":"Ricardo Gallardo lleva m\u00e1s apoyo a las familias de la capital con paquetes alimentarios"},"content":{"rendered":"\n<p><strong>\u2022&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; M\u00e1s de 16 mil hogares de la colonia Fovissste recibir\u00e1n el programa Seguridad Alimentaria cada 45 d\u00edas<\/strong><\/p>\n\n\n\n<p>M\u00e1s de 16 mil familias que habitan en la colonia Fovissste y fraccionamientos aleda\u00f1os de la capital, recibir\u00e1n m\u00e1s apoyo para acceder a una sana nutrici\u00f3n con el programa Seguridad Alimentaria, luego de que este mi\u00e9rcoles el Gobernador Ricardo Gallardo Cardona arranc\u00f3 la entrega del programa que les proporcionar\u00e1 20 kilos de productos de calidad cada 45 d\u00edas.<\/p>\n\n\n\n<p>Ante habitantes de colonias aleda\u00f1as que se reunieron para agradecer por los apoyos entregados, el Mandatario Estatal, expres\u00f3 su compromiso de continuar con reconstruyendo San Luis Potos\u00ed con m\u00e1s infraestructura como caminos, puentes, hospitales y escuelas, para que incremente el bienestar de las y los potosinos, adem\u00e1s de entregar programas sociales como las becas para adultos mayores y madres solteras, Seguridad Alimentaria, entre otros.<\/p>\n\n\n\n<p>Explic\u00f3 que, en tres a\u00f1os, el Gobierno Estatal ha realizado m\u00e1s que los \u00faltimos 30, de la herencia maldita, con 22 mil millones de pesos para obras, por lo que, anunci\u00f3 que seguir\u00e1 reconstruyendo las colonias, y pr\u00f3ximamente iniciar\u00e1 en Fovissste, Infonavit, Las Piedras, y otras cercanas, para dejar calles nuevas, \u00e1reas verdes con juegos infantiles y gimnasio al aire libre, rampas para personas con discapacidad y el arreglo de las escaleras de los edificios.<\/p>\n\n\n\n<p>El programa Seguridad Alimentaria es un programa dise\u00f1ado por el Sistema Estatal para el Desarrollo Integral de la Familia (DIF), para combatir la carencia alimentaria, a trav\u00e9s del cual se entregar\u00e1n casi 500 mil paquetes en las cuatro regiones lo que generar\u00e1 ahorros que podr\u00e1n destinarse a otras necesidades b\u00e1sicas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u2022&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; M\u00e1s de 16 mil hogares de la colonia Fovissste recibir\u00e1n el programa Seguridad Alimentaria cada 45 d\u00edas M\u00e1s de 16 mil familias que habitan en la colonia Fovissste y fraccionamientos aleda\u00f1os de la capital, recibir\u00e1n m\u00e1s apoyo para acceder a una sana nutrici\u00f3n con el programa Seguridad Alimentaria, luego de que este mi\u00e9rcoles el [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":10016,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[3],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/10015"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=10015"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/10015\/revisions"}],"predecessor-version":[{"id":10017,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/10015\/revisions\/10017"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/10016"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=10015"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=10015"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=10015"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}