{"id":10354,"date":"2024-11-04T15:33:00","date_gmt":"2024-11-04T15:33:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=10354"},"modified":"2024-11-05T22:34:40","modified_gmt":"2024-11-05T22:34:40","slug":"concejo-municipal-de-villa-de-pozos-instala-comision-de-servicios-municipales","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2024\/11\/04\/concejo-municipal-de-villa-de-pozos-instala-comision-de-servicios-municipales\/","title":{"rendered":"Concejo Municipal de Villa de Pozos instala Comisi\u00f3n de Servicios Municipales"},"content":{"rendered":"\n<ul>\n<li><strong>Se refuerza el compromiso de vigilar la atenci\u00f3n a las demandas ciudadanas en los servicios p\u00fablicos.<\/strong><\/li>\n<\/ul>\n\n\n\n<p>El Concejo Municipal de Villa de Pozos llev\u00f3 a cabo la instalaci\u00f3n de la Comisi\u00f3n de Servicios Municipales presidida por el regidor concejal Lauro Espinosa Nava, quien asumi\u00f3 el liderazgo de esta nueva comisi\u00f3n.<\/p>\n\n\n\n<p>Acompa\u00f1ado por el secretario general del Concejo Municipal de Villa de Pozos, Ren\u00e9 Oyarvide Ibarra, Espinosa Nava destac\u00f3 la importancia de los servicios p\u00fablicos dentro de esta administraci\u00f3n y el atender las necesidades m\u00e1s apremiantes de los ciudadanos.<\/p>\n\n\n\n<p>Enfatiz\u00f3 que la creaci\u00f3n de esta comisi\u00f3n responde a un compromiso con la transparencia y la participaci\u00f3n ciudadana, as\u00ed como el escuchar y canalizar las inquietudes de la poblaci\u00f3n en \u00e1reas como el agua potable, seguridad y el mantenimiento de espacios p\u00fablicos.<\/p>\n\n\n\n<p>El secretario general, Ren\u00e9 Oyarvide Ibarra dijo que esta sinergia entre el \u00e1rea a su cargo y la comisi\u00f3n refuerza la colaboraci\u00f3n entre diferentes instancias del gobierno municipal, lo que se espera se traduzca en un trabajo m\u00e1s coordinado y efectivo donde el compromiso ciudadano ser\u00e1 esencial para alcanzar estos objetivos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Concejo Municipal de Villa de Pozos llev\u00f3 a cabo la instalaci\u00f3n de la Comisi\u00f3n de Servicios Municipales presidida por el regidor concejal Lauro Espinosa Nava, quien asumi\u00f3 el liderazgo de esta nueva comisi\u00f3n. Acompa\u00f1ado por el secretario general del Concejo Municipal de Villa de Pozos, Ren\u00e9 Oyarvide Ibarra, Espinosa Nava destac\u00f3 la importancia de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":10355,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/10354"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=10354"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/10354\/revisions"}],"predecessor-version":[{"id":10356,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/10354\/revisions\/10356"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/10355"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=10354"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=10354"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=10354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}