{"id":10756,"date":"2024-11-16T13:00:00","date_gmt":"2024-11-16T13:00:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=10756"},"modified":"2024-11-18T04:51:57","modified_gmt":"2024-11-18T04:51:57","slug":"seguridad-alimentaria-llega-a-familias-de-villa-de-pozos","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2024\/11\/16\/seguridad-alimentaria-llega-a-familias-de-villa-de-pozos\/","title":{"rendered":"Seguridad alimentaria llega a familias de Villa de Pozos."},"content":{"rendered":"\n<p>El Concejo Municipal de Villa de Pozos es consciente de las necesidades de los grupos m\u00e1s vulnerables y est\u00e1 listo para desplegar los apoyos sociales que permitan mejorar la calidad de vida de sus habitantes afirm\u00f3 la Concejal Presidenta Teresa Rivera Acevedo, durante la entrega del Programa Alimentario a cargo de Gobierno del Estado de San Luis Potos\u00ed en la Colonia La Libertad, donde se distribuyeron m\u00e1s de mil paquetes alimentarios en apoyo de las familias de este municipio.<\/p>\n\n\n\n<p>Esta estrategia se lleva a cabo con el apoyo del Gobierno del Estado que encabeza Ricardo Gallardo Cardona, a trav\u00e9s de la Secretar\u00eda de Desarrollo Social y Regional (Sedesore), con la cual, cientos de familias en Villa de Pozos ser\u00e1n beneficiadas mensualmente con productos de la canasta b\u00e1sica de mayor calidad, que cubran las necesidades nutricionales b\u00e1sicas.<\/p>\n\n\n\n<p>Teresa Rivera, agradeci\u00f3 al Mandatario Estatal y destac\u00f3 que estos apoyos est\u00e1n encaminados a resolver toda una problem\u00e1tica que desafortunadamente mantuvo a Villa de Pozos, en el abandono y el rezago por al menos 40 a\u00f1os, siendo el traspatio de la capital potosina, ya que todos los impuestos se quedaban en los bolsillos de los funcionarios o bien se destinaban para los sectores m\u00e1s ricos de la ciudad.<\/p>\n\n\n\n<p>\u201cEs un reto muy grande que el d\u00eda de hoy estamos llevando, pero estamos a la mejor disposici\u00f3n de sacar adelante el municipio y hacerlo con bases s\u00f3lidas ustedes tienen un gobierno de puertas\u201d finaliz\u00f3 la Concejal Presidenta.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Concejo Municipal de Villa de Pozos es consciente de las necesidades de los grupos m\u00e1s vulnerables y est\u00e1 listo para desplegar los apoyos sociales que permitan mejorar la calidad de vida de sus habitantes afirm\u00f3 la Concejal Presidenta Teresa Rivera Acevedo, durante la entrega del Programa Alimentario a cargo de Gobierno del Estado de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":10757,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/10756"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=10756"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/10756\/revisions"}],"predecessor-version":[{"id":10758,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/10756\/revisions\/10758"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/10757"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=10756"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=10756"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=10756"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}