{"id":10798,"date":"2024-11-18T12:33:00","date_gmt":"2024-11-18T12:33:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=10798"},"modified":"2024-11-19T04:00:55","modified_gmt":"2024-11-19T04:00:55","slug":"villa-de-pozos-reforzara-la-salud-con-integracion-a-la-red-de-municipios-saludables","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2024\/11\/18\/villa-de-pozos-reforzara-la-salud-con-integracion-a-la-red-de-municipios-saludables\/","title":{"rendered":"Villa de Pozos reforzar\u00e1 la salud con integraci\u00f3n a la Red de Municipios Saludables"},"content":{"rendered":"\n<ul>\n<li><strong>Con apoyo de los Servicios de Salud, busca certificarse como Municipio Saludable<\/strong><\/li>\n<\/ul>\n\n\n\n<p>El Concejo Municipal de Villa de Pozos a trav\u00e9s de su Comisi\u00f3n de Salud, inici\u00f3 un proceso fundamental para mejorar las condiciones de vida de sus habitantes, con el objetivo de integrarse a la Red de Municipios Saludables que promueve el gobierno federal.<\/p>\n\n\n\n<p>Lo anterior luego de llevar a cabo la primera sesi\u00f3n de la Comisi\u00f3n de Salud presidida por&nbsp; Mar\u00eda Luisa Zavala L\u00f3pez, en la que estuvieron presentes la Presidenta Concejal, Teresa Rivera Acevedo y directivos de la Jurisdicci\u00f3n Sanitaria no.1 de los Servicios de Salud, quienes dieron a conocer los procesos que debe de pasar el reci\u00e9n creado municipio con el fin de certificarse como un Municipios Saludables.<\/p>\n\n\n\n<p>La Presidenta Concejal, Teresa Rivera Acevedo &nbsp;dijo que con la participaci\u00f3n del municipio en estas acciones se convierte en una entidad proactiva en la promoci\u00f3n de la salud, que no solo se preocupa por la atenci\u00f3n m\u00e9dica, sino tambi\u00e9n por la creaci\u00f3n de espacios y programas que fomenten h\u00e1bitos saludables entre la poblaci\u00f3n y el apoyo de los Servicios de Salud en el Estado y la participaci\u00f3n activa de la sociedad, el municipio est\u00e1 dando pasos s\u00f3lidos hacia un futuro m\u00e1s saludable y sostenible para todos.<\/p>\n\n\n\n<p>Por su parte la presidenta de la comisi\u00f3n de Salud, Maria Luisa Zavala L\u00f3pez resalt\u00f3 que para llegar a la certificaci\u00f3n como un municipio saludable implica un compromiso con el bienestar colectivo, ya que esta red fomenta la colaboraci\u00f3n entre diversas instituciones, tanto del sector p\u00fablico como privado, para implementar pol\u00edticas que favorezcan la salud integral.<\/p>\n\n\n\n<p>Finalmente, Alma Monlui Mart\u00ednez, de la Jurisdicci\u00f3n Sanitaria No. 1 de los Servicios de Salud, explic\u00f3 los pasos para dicha certificaci\u00f3n es un proceso no solo busca ofrecer atenci\u00f3n m\u00e9dica m\u00e1s eficiente, sino tambi\u00e9n implementar programas preventivos en \u00e1reas como nutrici\u00f3n, higiene, salud mental y control de enfermedades cr\u00f3nicas, por lo que trabajar\u00e1n de la mano con el municipio para lograr este cometido.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Concejo Municipal de Villa de Pozos a trav\u00e9s de su Comisi\u00f3n de Salud, inici\u00f3 un proceso fundamental para mejorar las condiciones de vida de sus habitantes, con el objetivo de integrarse a la Red de Municipios Saludables que promueve el gobierno federal. Lo anterior luego de llevar a cabo la primera sesi\u00f3n de la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":10799,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/10798"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=10798"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/10798\/revisions"}],"predecessor-version":[{"id":10800,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/10798\/revisions\/10800"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/10799"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=10798"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=10798"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=10798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}