{"id":11039,"date":"2024-11-26T10:33:00","date_gmt":"2024-11-26T10:33:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=11039"},"modified":"2024-11-26T17:35:18","modified_gmt":"2024-11-26T17:35:18","slug":"gobierno-del-estado-da-mantenimiento-a-sismografos","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2024\/11\/26\/gobierno-del-estado-da-mantenimiento-a-sismografos\/","title":{"rendered":"Gobierno del estado da mantenimiento a sism\u00f3grafos"},"content":{"rendered":"\n<ul>\n<li><strong>Protecci\u00f3n Civil Estatal garantiza internet estable, as\u00ed como centrado y estabilizaci\u00f3n del equipo<\/strong><\/li>\n<\/ul>\n\n\n\n<p>La Coordinaci\u00f3n Estatal de Protecci\u00f3n Civil (CEPC) y el Servicio Sismol\u00f3gico Nacional (SSN) dan mantenimiento a los sism\u00f3grafos ubicados en Ciudad Valles, Aquism\u00f3n y Villa Hidalgo, para garantizar que funcionen en \u00f3ptimas condiciones y mantener vigente el monitoreo de la federaci\u00f3n sobre los sismos que se registren en la entidad.<\/p>\n\n\n\n<p>El director de la dependencia, Mauricio Ordaz Flores, mencion\u00f3 que, siguiendo la instrucci\u00f3n del Gobernador Ricardo Gallardo Cardona de brindar m\u00e1s apoyo a las familias potosinas con acciones en prevenci\u00f3n, Protecci\u00f3n Civil Estatal realiza revisiones peri\u00f3dicas para asegurar que haya un internet estable, as\u00ed como el centrado y estabilizaci\u00f3n del equipo.<\/p>\n\n\n\n<p>Los sism\u00f3grafos y los restantes, dan cobertura a todo el Estado con informaci\u00f3n en tiempo real para el SSN, desde Villa Hidalgo, El Naranjo, Ciudad Valles, Tamasopo, San Ciro de Acosta, Armadillo de los Infante, Cerritos, Ray\u00f3n, Aquism\u00f3n, Ciudad Fern\u00e1ndez, Matehuala y en la capital.<\/p>\n\n\n\n<p>El funcionario dio a conocer que en lo que va del 2024, se han registrado ochenta y ocho sismos en San Luis Potos\u00ed, percibidos por la red Sismol\u00f3gica del Estado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Coordinaci\u00f3n Estatal de Protecci\u00f3n Civil (CEPC) y el Servicio Sismol\u00f3gico Nacional (SSN) dan mantenimiento a los sism\u00f3grafos ubicados en Ciudad Valles, Aquism\u00f3n y Villa Hidalgo, para garantizar que funcionen en \u00f3ptimas condiciones y mantener vigente el monitoreo de la federaci\u00f3n sobre los sismos que se registren en la entidad. El director de la dependencia, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":11040,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[3],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/11039"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=11039"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/11039\/revisions"}],"predecessor-version":[{"id":11041,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/11039\/revisions\/11041"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/11040"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=11039"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=11039"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=11039"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}