{"id":11176,"date":"2024-11-30T14:10:00","date_gmt":"2024-11-30T14:10:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=11176"},"modified":"2024-12-01T03:14:13","modified_gmt":"2024-12-01T03:14:13","slug":"ayuntamiento-de-soledad-prepara-foro-ciudadano-como-parte-de-integracion-de-plan-municipal-de-desarrollo-2024-2027","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2024\/11\/30\/ayuntamiento-de-soledad-prepara-foro-ciudadano-como-parte-de-integracion-de-plan-municipal-de-desarrollo-2024-2027\/","title":{"rendered":"Ayuntamiento de Soledad prepara foro ciudadano como parte de integraci\u00f3n de Plan Municipal de Desarrollo 2024-2027"},"content":{"rendered":"\n<ul>\n<li><strong>Con foros, buzones y plataformas digitales, el Gobierno Municipal de Soledad de Graciano S\u00e1nchez contin\u00faa invitando a la ciudadan\u00eda en general a participar en la Consulta Ciudadana, mediante propuestas y opiniones.<\/strong><\/li>\n<\/ul>\n\n\n\n<p>El Gobierno Municipal de Soledad de Graciano S\u00e1nchez, comprometido con fomentar la participaci\u00f3n ciudadana en la toma de decisiones que impactan en crecimiento del municipio, invita a toda la ciudadan\u00eda en general a participar en el Foro de Consulta Ciudadana, el pr\u00f3ximo 6 de diciembre, como parte del cierre de la convocatoria que busca recoger opiniones, propuestas y solicitudes que ser\u00e1n la base para construir el Plan Municipal de Desarrollo 2024-2027.<\/p>\n\n\n\n<p>La Consulta Ciudadana, actualmente vigente, ofrece m\u00faltiples mecanismos de participaci\u00f3n para garantizar que todas las voces sean escuchadas, entre ellos destacan los buzones de consulta instalados en ubicaciones clave como la Presidencia Municipal, el Sistema Municipal DIF, las Unidades B\u00e1sicas de Rehabilitaci\u00f3n (UBR), instalaciones de la Comandancia Municipal, consultorios m\u00e9dicos gratuitos, Bibliotecas Municipales y oficinas administrativas, entre otros espacios.<\/p>\n\n\n\n<p>Adem\u00e1s, la ciudadan\u00eda podr\u00e1 expresar sus ideas en el Foro de Consulta Popular, responder encuestas presenciales en diversos puntos del municipio y participar de manera digital a trav\u00e9s de la p\u00e1gina oficial del Ayuntamiento [www.municipiosoledad.gob.mx] y un formulario en l\u00ednea.<\/p>\n\n\n\n<p>El Ayuntamiento extiende la invitaci\u00f3n a organizaciones de la sociedad civil, colectivos, personas con discapacidad, ejidatarios, empresarios y todos los sectores sociales para sumarse a esta iniciativa que promueve la planeaci\u00f3n democr\u00e1tica y la mejora de la calidad de vida de las y los soledenses.<\/p>\n\n\n\n<p>Para m\u00e1s informaci\u00f3n sobre las fechas y ubicaciones espec\u00edficas del foro, as\u00ed como acceso al formulario digital, consulta nuestras redes sociales oficiales, en Facebook: Municipio de Soledad de Graciano S\u00e1nchez; Instagram y X: @MunicipioSGS.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Gobierno Municipal de Soledad de Graciano S\u00e1nchez, comprometido con fomentar la participaci\u00f3n ciudadana en la toma de decisiones que impactan en crecimiento del municipio, invita a toda la ciudadan\u00eda en general a participar en el Foro de Consulta Ciudadana, el pr\u00f3ximo 6 de diciembre, como parte del cierre de la convocatoria que busca recoger [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":11177,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[10],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/11176"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=11176"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/11176\/revisions"}],"predecessor-version":[{"id":11178,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/11176\/revisions\/11178"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/11177"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=11176"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=11176"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=11176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}