{"id":1154,"date":"2024-03-29T23:15:00","date_gmt":"2024-03-29T23:15:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=1154"},"modified":"2024-03-30T20:50:17","modified_gmt":"2024-03-30T20:50:17","slug":"miles-de-visitantes-viven-la-majestuosidad-de-la-procesion-del-silencio","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2024\/03\/29\/miles-de-visitantes-viven-la-majestuosidad-de-la-procesion-del-silencio\/","title":{"rendered":"Miles de visitantes viven la majestuosidad de la Procesi\u00f3n del Silencio\u00a0"},"content":{"rendered":"\n<ul>\n<li><strong>Desde antes de las 17:00 horas de este Viernes Santo, turistas locales, nacionales y extranjeros inundaron las calles del Centro Hist\u00f3rico<\/strong><\/li>\n<\/ul>\n\n\n\n<p>La Procesi\u00f3n del Silencio en San Luis Potos\u00ed, tradici\u00f3n cultural-religiosa considerada como una de las m\u00e1s importantes en su tipo a nivel nacional e internacional, dio muestra una vez m\u00e1s de su majestuosidad, con la participaci\u00f3n de 2 mil integrantes de las diferentes cofrad\u00edas, quienes acompa\u00f1aron a la virgen en su luto mediante la representaci\u00f3n del viacrusis impresionando a miles de personas.<\/p>\n\n\n\n<p>Desde antes de las 17:00 horas de este Viernes Santo, turistas locales, nacionales y extranjeros inundaron las calles del Centro Hist\u00f3rico para presenciar esta importante tradici\u00f3n con mayor arraigo entre la sociedad de San Luis Potos\u00ed, declarada desde 2013 Patrimonio Cultural del Estado.<\/p>\n\n\n\n<p>Entre el silencio y los tambores cada cofrad\u00eda se identific\u00f3 por los colores alusivos a sus templos, los costaleros cargaron las pesadas im\u00e1genes, damas, nazarenos, encapuchados y cofrades tambi\u00e9n se mostraron penitentes.<\/p>\n\n\n\n<p>El Poder Ejecutivo del Estado, a trav\u00e9s de las Secretar\u00edas de Cultura (Secult) y Turismo (Sectur) difundieron la Procesi\u00f3n del Silencio, mientras que las corporaciones de seguridad y protecci\u00f3n civil estatal, garantizaron la paz y el orden.<\/p>\n\n\n\n<p>Las y los participantes de la Procesi\u00f3n del Silencio, iniciaron su recorrido en el templo del Carmen, continuando por las calles de Viller\u00edas, Universidad, Aldama, Galeana, Independencia, Venustiano Carranza, Madero, 5 de mayo, Jard\u00edn Hidalgo y Manuel Jos\u00e9 Oth\u00f3n, regresando al punto de partida.<\/p>\n\n\n\n<p>Esta informaci\u00f3n es de inter\u00e9s p\u00fablico, ajena a cualquier inter\u00e9s particular o alg\u00fan partido pol\u00edtico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Procesi\u00f3n del Silencio en San Luis Potos\u00ed, tradici\u00f3n cultural-religiosa considerada como una de las m\u00e1s importantes en su tipo a nivel nacional e internacional, dio muestra una vez m\u00e1s de su majestuosidad, con la participaci\u00f3n de 2 mil integrantes de las diferentes cofrad\u00edas, quienes acompa\u00f1aron a la virgen en su luto mediante la representaci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1155,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[6],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/1154"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=1154"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/1154\/revisions"}],"predecessor-version":[{"id":1156,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/1154\/revisions\/1156"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/1155"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=1154"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=1154"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=1154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}