{"id":11595,"date":"2024-12-13T14:30:00","date_gmt":"2024-12-13T14:30:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=11595"},"modified":"2024-12-14T05:27:27","modified_gmt":"2024-12-14T05:27:27","slug":"ricardo-gallardo-anuncia-la-renovacion-de-la-central-de-abastos","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2024\/12\/13\/ricardo-gallardo-anuncia-la-renovacion-de-la-central-de-abastos\/","title":{"rendered":"Ricardo Gallardo anuncia la renovaci\u00f3n de la Central de Abastos"},"content":{"rendered":"\n<ul>\n<li><strong>Con una inversi\u00f3n de 350 millones de pesos, convertir\u00e1 este espacio en uno m\u00e1s moderno y seguro<\/strong><\/li>\n<\/ul>\n\n\n\n<p>El Gobernador Ricardo Gallardo Cardona anunci\u00f3 que con una inversi\u00f3n de 350 millones de pesos se har\u00e1 una renovaci\u00f3n integral a la Central de Abastos, cambiando por completo la imagen de este espacio al que diariamente acuden las y los potosinos, convirti\u00e9ndose en uno m\u00e1s moderno y seguro.<\/p>\n\n\n\n<p>El Mandatario Estatal detall\u00f3 que en marzo del 2025 arrancar\u00edan labores y el proyecto contempla calles nuevas, reparaci\u00f3n de las bodegas, cambio de alumbrado y la creaci\u00f3n de una comandancia de Seguridad P\u00fablica con un sistema C2 o C3 que permita mantener un monitoreo constante del entorno. Sobre esto \u00faltimo, tambi\u00e9n mencion\u00f3 que se contar\u00e1 con dos patrullas encargadas del cuidado exclusivo de la Central de Abastos.<\/p>\n\n\n\n<p>Ricardo Gallardo destac\u00f3 que, se har\u00e1 un cambio absoluto en este entorno con la intenci\u00f3n de entregar a las y los comerciantes, usuarios y clientes una Central de Abastos totalmente nueva y renovada.<\/p>\n\n\n\n<p>El Gobernador dijo que se busca brindar m\u00e1s apoyo a las y los comerciantes para que puedan seguir haciendo uso de estas instalaciones, pero ahora en las condiciones que se merecen luego de que la herencia maldita mantuvo en abandono a este sector tan importante para la econom\u00eda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Gobernador Ricardo Gallardo Cardona anunci\u00f3 que con una inversi\u00f3n de 350 millones de pesos se har\u00e1 una renovaci\u00f3n integral a la Central de Abastos, cambiando por completo la imagen de este espacio al que diariamente acuden las y los potosinos, convirti\u00e9ndose en uno m\u00e1s moderno y seguro. El Mandatario Estatal detall\u00f3 que en marzo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":11596,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[3],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/11595"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=11595"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/11595\/revisions"}],"predecessor-version":[{"id":11597,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/11595\/revisions\/11597"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/11596"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=11595"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=11595"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=11595"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}