{"id":1163,"date":"2024-03-30T21:26:20","date_gmt":"2024-03-30T21:26:20","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=1163"},"modified":"2024-03-30T21:26:20","modified_gmt":"2024-03-30T21:26:20","slug":"invitan-al-xxvii-festival-del-son","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2024\/03\/30\/invitan-al-xxvii-festival-del-son\/","title":{"rendered":"Invitan al XXVII Festival del Son"},"content":{"rendered":"\n<ul>\n<li><strong>Se llevar\u00e1 a cabo el domingo 31 de marzo, en el Museo Nacional de la M\u00e1scara, con la participaci\u00f3n especial del Dr. Chessani y sus Huapangueros de Rioverde<\/strong><\/li>\n<\/ul>\n\n\n\n<p>El Poder Ejecutivo del Estado de San Luis Potos\u00ed a trav\u00e9s de la Secretar\u00eda de Cultura (Secult), en el marco de las actividades culturales de Semana Santa, invita al p\u00fablico en general a disfrutar del XXVII Festival del Son, que se realizar\u00e1 el pr\u00f3ximo domingo 31 de marzo a las 18:00 horas, en el Museo Nacional de la M\u00e1scara, entrada libre.<\/p>\n\n\n\n<p>En esta edici\u00f3n participar\u00e1 por 27 a\u00f1os consecutivos el Dr. Chessani y sus Huapangueros de Rioverde, uno de los grupos exponentes de son arribe\u00f1o y huasteco con mayor tradici\u00f3n y reconocimiento nacional e internacional, por compartir la riqueza musical de la regi\u00f3n Media de la Entidad, en la capital potosina.<\/p>\n\n\n\n<p>Adem\u00e1s participar\u00e1n compa\u00f1\u00edas de folclor que bailar\u00e1n al ritmo del son arribe\u00f1o y huasteco, as\u00ed como el acompa\u00f1amiento de otros artistas invitados y la interacci\u00f3n con el p\u00fablico asistente.<\/p>\n\n\n\n<p>Esta actividad es p\u00fablica, de car\u00e1cter cultural y educativa, ajena a cualquier inter\u00e9s o partido pol\u00edtico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Poder Ejecutivo del Estado de San Luis Potos\u00ed a trav\u00e9s de la Secretar\u00eda de Cultura (Secult), en el marco de las actividades culturales de Semana Santa, invita al p\u00fablico en general a disfrutar del XXVII Festival del Son, que se realizar\u00e1 el pr\u00f3ximo domingo 31 de marzo a las 18:00 horas, en el Museo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1164,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[6],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/1163"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=1163"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/1163\/revisions"}],"predecessor-version":[{"id":1165,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/1163\/revisions\/1165"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/1164"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=1163"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=1163"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=1163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}