{"id":11645,"date":"2024-12-15T21:44:00","date_gmt":"2024-12-15T21:44:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=11645"},"modified":"2024-12-16T06:47:12","modified_gmt":"2024-12-16T06:47:12","slug":"gran-inauguracion-de-pista-de-hielo-en-soledad-se-suma-a-actividades-navidenas-para-las-familias","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2024\/12\/15\/gran-inauguracion-de-pista-de-hielo-en-soledad-se-suma-a-actividades-navidenas-para-las-familias\/","title":{"rendered":"Gran inauguraci\u00f3n de pista de hielo en Soledad, se suma a actividades navide\u00f1as para las familias"},"content":{"rendered":"\n<ul>\n<li><strong>Con el impulso del Alcalde, Juan Manuel Navarro Mu\u00f1iz, este atractivo se consolida un a\u00f1o m\u00e1s para divertir a chicos y grandes en la Plaza principal.<\/strong><\/li>\n<\/ul>\n\n\n\n<p>Con un show espectacular a cargo de la patinadora art\u00edstica y potosina, Kina Catrina, fue inaugurada la grandiosa Pista de Hielo en la Plaza principal de Soledad de Graciano S\u00e1nchez, ante cientos de familias que se dieron cita para divertirse y vivir la navidad en el coraz\u00f3n del municipio, como parte de las actividades de temporada que el Alcalde Juan Manuel Navarro Mu\u00f1iz, ha impulsado para el disfrute de la poblaci\u00f3n.<\/p>\n\n\n\n<p>Alrededor de las 8 de la noche, se abri\u00f3 la pista para presentar a la artista sobre hielo, con un show musical denominado \u00abNoche de Paz\u00bb, encantando a ni\u00f1os, ni\u00f1as, adolescentes y adultos presentes. Las luces y los villancicos ofrecieron un momento de alegr\u00eda y emoci\u00f3n para las y los asistentes, quienes pudieron disfrutar de un ambiente navide\u00f1o \u00fanico en la ciudad.<\/p>\n\n\n\n<p>Este atractivo cumple con la finalidad de incentivar la cohesi\u00f3n social y traer la ilusi\u00f3n de la Navidad para las y los habitantes de Soledad, para que vivan noches \u00fanicas e inolvidables junto a sus seres queridos. La Pista de Hielo estar\u00e1 abierta todos los d\u00edas desde las 12 del d\u00eda y hasta las 9 de la noche, hasta el pr\u00f3ximo 8 de enero.<\/p>\n\n\n\n<p>Tal y como lo anunci\u00f3 el Alcalde, Navarro Mu\u00f1iz, la atractiva Pista de Hielo mide 40 por 20 metros y caben simult\u00e1neamente hasta 70 personas, para que nadie se quede sin vivir la magia y la felicidad de esta temporada.<\/p>\n\n\n\n<p>A la par, el Alcalde Juan Manuel Navarro, contin\u00faa recorriendo las colonias y comunidades llevando juguetes, m\u00fasica y un mensaje de paz y uni\u00f3n a las y los habitantes, a trav\u00e9s de las Posadas Navide\u00f1as. Este domingo, visit\u00f3 San Isidro, San Felipe y La Lomita, con mucho entusiasmo para alegrar a las familias enteras.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con un show espectacular a cargo de la patinadora art\u00edstica y potosina, Kina Catrina, fue inaugurada la grandiosa Pista de Hielo en la Plaza principal de Soledad de Graciano S\u00e1nchez, ante cientos de familias que se dieron cita para divertirse y vivir la navidad en el coraz\u00f3n del municipio, como parte de las actividades de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":11646,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[10],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/11645"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=11645"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/11645\/revisions"}],"predecessor-version":[{"id":11647,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/11645\/revisions\/11647"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/11646"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=11645"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=11645"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=11645"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}