{"id":11655,"date":"2024-12-16T09:50:00","date_gmt":"2024-12-16T09:50:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=11655"},"modified":"2024-12-16T21:37:43","modified_gmt":"2024-12-16T21:37:43","slug":"ceeav-brindara-apoyo-en-temporada-decembrina","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2024\/12\/16\/ceeav-brindara-apoyo-en-temporada-decembrina\/","title":{"rendered":"CEEAV brindar\u00e1 apoyo en temporada decembrina"},"content":{"rendered":"\n<ul>\n<li><strong>Tendr\u00e1 horarios normales para quienes soliciten los servicios<\/strong><\/li>\n<\/ul>\n\n\n\n<p>La Comisi\u00f3n Ejecutiva Estatal de Atenci\u00f3n a V\u00edctimas (CEEAV) mantendr\u00e1 sus servicios y el apoyo a las y los potosinos, durante la temporada decembrina, y lo que resta del a\u00f1o, con personal de confianza en el horario habitual, adem\u00e1s de establecer guardias con la Unidad de Primer Contacto y Atenci\u00f3n Inmediata.<\/p>\n\n\n\n<p>El comisionado de Atenci\u00f3n a V\u00edctimas, Miguel \u00c1ngel Garc\u00eda Amaro, inform\u00f3 que en seguimiento a la instrucci\u00f3n del Gobernador del Estado, Ricardo Gallardo Cardona, ofrecer\u00e1n el servicio de las \u00e1reas psicol\u00f3gica, jur\u00eddica y de trabajo Social de forma regular, con servicios oportunos y de calidad a las v\u00edctimas directas o indirectas de alg\u00fan delito \u201cel trabajo de esta Comisi\u00f3n no puede detenerse y ser\u00e1 de manera presencial\u201d.<\/p>\n\n\n\n<p>El horario de la CEEAV es de 8:00 a 20:00 horas, mientras que en el periodo vacacional decembrino que inicia este 16 de diciembre, brindar\u00e1n atenci\u00f3n en guardias o v\u00eda telef\u00f3nica en m\u00f3dulos instalados en la zona metropolitana y en los municipios de Matehuala, Ciudad Valles, Rioverde, Tamazunchale, Tancanhuitz y Ciudad del Ma\u00edz.<\/p>\n\n\n\n<p>La atenci\u00f3n ser\u00e1 en las instalaciones del CEEAV ubicada en la calle de Ignacio L\u00f3pez Ray\u00f3n n\u00famero 450, en el Centro Hist\u00f3rico o bien al tel\u00e9fono 444 8120578 y 444 812 1004; el m\u00f3dulo de la Fiscal\u00eda General del Estado (FGE) con tel\u00e9fono 444 812 2624 extensiones 1324 y 1325 y el m\u00f3dulo del Centro Integral de Justicia Penal; Matehuala, 488 887 7024; Ciudad Valles, 481 381 03 68; Rioverde, 487 100 90 63; Tancanhuitz, 482 367 10 84 y tambi\u00e9n pueden acudir de forma presencial en el municipio de Tamazunchale en sus instalaciones ubicadas en Xochiquetzal esquina Tomiy\u00e1huatl S\/N Barrio Real Zacatipan y en Ciudad del Ma\u00edz, Boulevard Miguel Barrag\u00e1n S\/N en la zona centro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Comisi\u00f3n Ejecutiva Estatal de Atenci\u00f3n a V\u00edctimas (CEEAV) mantendr\u00e1 sus servicios y el apoyo a las y los potosinos, durante la temporada decembrina, y lo que resta del a\u00f1o, con personal de confianza en el horario habitual, adem\u00e1s de establecer guardias con la Unidad de Primer Contacto y Atenci\u00f3n Inmediata. El comisionado de Atenci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":11656,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[3],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/11655"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=11655"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/11655\/revisions"}],"predecessor-version":[{"id":11657,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/11655\/revisions\/11657"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/11656"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=11655"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=11655"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=11655"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}