{"id":1352,"date":"2024-04-03T06:23:00","date_gmt":"2024-04-03T06:23:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=1352"},"modified":"2024-04-04T02:48:06","modified_gmt":"2024-04-04T02:48:06","slug":"once-potosinos-califican-a-nacionales-conade-en-ciclismo-de-montana","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2024\/04\/03\/once-potosinos-califican-a-nacionales-conade-en-ciclismo-de-montana\/","title":{"rendered":"Once potosinos califican a Nacionales Conade en Ciclismo de Monta\u00f1a"},"content":{"rendered":"\n<p>Tras concluir la exhaustiva prueba de ciclismo de monta\u00f1a de los Juegos Macro Regionales CONADE, once pedalistas potosinos consiguen la calificaci\u00f3n a la fase Nacional.<\/p>\n\n\n\n<p>En total acudieron 18 competidores a tomar parte del evento celebrado en la pista \u00abTejones\u00bb del municipio de Allende en el estado de Nuevo Le\u00f3n.<\/p>\n\n\n\n<p>Escenario de 4.9 kil\u00f3metros incluyendo un cerro denominado \u00abEl Mirador\u00bb.<\/p>\n\n\n\n<p>Se compiti\u00f3 en las categor\u00edas Juvenil \u00abA\u00bb, Juvenil \u00abB&#8217;, Juvenil \u00abC\u00bb, as\u00ed como Sub 23.<\/p>\n\n\n\n<p>Las y los calificados son: Margarita Gonz\u00e1lez P\u00e9rez de Ciudad Valles, Alma Emily Alarc\u00f3n Gonz\u00e1lez de Villa de Reyes y Yahel Alexander Alarc\u00f3n Gonz\u00e1lez de Rioverde en Juvenil \u00abA\u00bb.<\/p>\n\n\n\n<p>Franco Emmanuel de Blas Moreno y El\u00edas Ju\u00e1rez Segura de Villa de Reyes en la categor\u00eda Juvenil \u00abB\u00bb.<\/p>\n\n\n\n<p>Con ellos Owen Josimar Sandoval Gallegos de Matehuala, \u00c1ngel Andr\u00e9s P\u00e9rez de Rioverde y Citlaly Yaretzel Castillo Renter\u00eda de Villa de Reyes de la categor\u00eda Juvenil \u00abC\u00bb.<\/p>\n\n\n\n<p>Y de la categor\u00eda Sub 23 calificaron Ram\u00f3n Emir Eguia Vallejo de Matehuala, Samantha Guadalupe Alarc\u00f3n Gonz\u00e1lez de Villa de Reyes y Kristell Anah\u00ed Hern\u00e1ndez D\u00edaz de Ciudad Fern\u00e1ndez.<\/p>\n\n\n\n<p>Las y los calificados obtuvieron el derecho de representar a San Luis Potos\u00ed en la fase Nacional que se llevar\u00e1 a cabo en Jalisco.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tras concluir la exhaustiva prueba de ciclismo de monta\u00f1a de los Juegos Macro Regionales CONADE, once pedalistas potosinos consiguen la calificaci\u00f3n a la fase Nacional. En total acudieron 18 competidores a tomar parte del evento celebrado en la pista \u00abTejones\u00bb del municipio de Allende en el estado de Nuevo Le\u00f3n. Escenario de 4.9 kil\u00f3metros incluyendo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1353,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[5],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/1352"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=1352"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/1352\/revisions"}],"predecessor-version":[{"id":1354,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/1352\/revisions\/1354"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/1353"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=1352"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=1352"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=1352"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}