{"id":13966,"date":"2025-02-22T09:51:00","date_gmt":"2025-02-22T09:51:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=13966"},"modified":"2025-02-22T20:59:13","modified_gmt":"2025-02-22T20:59:13","slug":"historica-presentacion-la-seleccion-mexicana-de-basquetbol-vencio-a-nicaragua-en-slp","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2025\/02\/22\/historica-presentacion-la-seleccion-mexicana-de-basquetbol-vencio-a-nicaragua-en-slp\/","title":{"rendered":"Hist\u00f3rica presentaci\u00f3n: la Selecci\u00f3n Mexicana de B\u00e1squetbol venci\u00f3 a Nicaragua en SLP"},"content":{"rendered":"\n<ul>\n<li><strong>Su pr\u00f3ximo encuentro ser\u00e1 el 24 de febrero ante Canad\u00e1 en la Arena Potos\u00ed<\/strong><\/li>\n<\/ul>\n\n\n\n<p>Con una impresionante demostraci\u00f3n de buen baloncesto, la Selecci\u00f3n Mexicana de B\u00e1squetbol vivi\u00f3 una hist\u00f3rica presentaci\u00f3n en San Luis Potos\u00ed, al derrotar a Nicaragua con un marcador final de 107-57. Este encuentro fue posible gracias al apoyo en deporte brindado por la administraci\u00f3n del Gobernador Ricardo Gallardo Cardona, quien ha impulsado la organizaci\u00f3n de eventos de alto nivel en la entidad.<\/p>\n\n\n\n<p>El equipo mexicano mostr\u00f3 su dominio desde el primer periodo, logrando una ventaja de 18 puntos al finalizar 31-13 sobre Nicaragua. En el segundo periodo, la diferencia se ampli\u00f3 a 65-35, reflejando el s\u00f3lido control del juego.<\/p>\n\n\n\n<p>Durante la segunda mitad, la&nbsp; Selecci\u00f3n Mexicana mantuvo su intensidad, lo que se reflej\u00f3 en el marcador 88-38 al final del tercer periodo y 107-57 al cierre del encuentro. La afici\u00f3n potosina se mantuvo animada y entregada durante todo el juego, especialmente con jugadas espectaculares de Karim L\u00f3pez, quien cautiv\u00f3 a los presentes con sus impresionantes clavadas.<\/p>\n\n\n\n<p>Con esta victoria, la Selecci\u00f3n Mexicana de B\u00e1squetbol ya est\u00e1 en preparaci\u00f3n para su pr\u00f3ximo reto, enfrent\u00e1ndose a Canad\u00e1 en un emocionante duelo que se llevar\u00e1 a cabo el lunes 24 de febrero en la Majestuosa Arena Potos\u00ed a las 19:00 horas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con una impresionante demostraci\u00f3n de buen baloncesto, la Selecci\u00f3n Mexicana de B\u00e1squetbol vivi\u00f3 una hist\u00f3rica presentaci\u00f3n en San Luis Potos\u00ed, al derrotar a Nicaragua con un marcador final de 107-57. Este encuentro fue posible gracias al apoyo en deporte brindado por la administraci\u00f3n del Gobernador Ricardo Gallardo Cardona, quien ha impulsado la organizaci\u00f3n de eventos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":13967,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[5],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/13966"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=13966"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/13966\/revisions"}],"predecessor-version":[{"id":13968,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/13966\/revisions\/13968"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/13967"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=13966"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=13966"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=13966"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}