{"id":13992,"date":"2025-02-22T11:30:00","date_gmt":"2025-02-22T11:30:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=13992"},"modified":"2025-02-22T23:42:31","modified_gmt":"2025-02-22T23:42:31","slug":"recaudacion-de-predial-se-destinara-a-obras-y-acciones-en-villa-de-pozos","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2025\/02\/22\/recaudacion-de-predial-se-destinara-a-obras-y-acciones-en-villa-de-pozos\/","title":{"rendered":"Recaudaci\u00f3n de predial se destinar\u00e1 a obras y acciones en Villa de Pozos"},"content":{"rendered":"\n<p><strong>&#8211;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Se recaud\u00f3 m\u00e1s de 20 millones de pesos en enero, de los 7 millones que reportaba San Luis cuando Pozos era delegaci\u00f3n.<\/strong><\/p>\n\n\n\n<p>&nbsp;El Concejo Municipal de Villa de Pozos, logr\u00f3 superar las expectativas en la primera recaudaci\u00f3n del predial ya como municipio, pues en tan solo un mes recaud\u00f3 m\u00e1s de 20 millones de los 7 millones de pesos que reportaban cuando era delegaci\u00f3n.<\/p>\n\n\n\n<p>El Secretario General del Concejo Municipal, Ren\u00e9 Oyarvide Ibarra, destac\u00f3 que este resultado es producto del compromiso y colaboraci\u00f3n de los habitantes del municipio, quienes han acudido de manera activa a las diferentes oficinas para cumplir con su pago, ahora lo recaudado s\u00ed se ver\u00e1 reflejado en obras y acciones&nbsp; para beneficio de las y los ciudadanos y se garantizar\u00e1 un desarrollo integral para Villa de Pozos.<\/p>\n\n\n\n<p>Asimismo, Oyarvide Ibarra mencion\u00f3 que, durante el mes de febrero, el municipio sigue contando con el descuento del 10% en el pago del predial, lo cual incentiva a m\u00e1s ciudadanos a cumplir con su obligaci\u00f3n fiscal, lo que permitir\u00e1 a la administraci\u00f3n municipal seguir con su plan de trabajo enfocado en el mejoramiento de la infraestructura y los servicios para todos los habitantes de la localidad.<\/p>\n\n\n\n<p>Oyarvide Ibarra exhort\u00f3 a los contribuyentes que a\u00fan no cumplen con su obligaci\u00f3n fiscal a que se acerquen a cualquiera de los cuatro puntos de cobro que implement\u00f3 el concejo para el pago de este impuesto para que aproveche los \u00faltimos d\u00edas del descuento que se aplica en febrero o bien el descuento del 5% que se aplica en marzo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8211;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Se recaud\u00f3 m\u00e1s de 20 millones de pesos en enero, de los 7 millones que reportaba San Luis cuando Pozos era delegaci\u00f3n. &nbsp;El Concejo Municipal de Villa de Pozos, logr\u00f3 superar las expectativas en la primera recaudaci\u00f3n del predial ya como municipio, pues en tan solo un mes recaud\u00f3 m\u00e1s de 20 millones de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":13993,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/13992"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=13992"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/13992\/revisions"}],"predecessor-version":[{"id":13994,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/13992\/revisions\/13994"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/13993"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=13992"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=13992"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=13992"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}