{"id":1472,"date":"2024-04-05T08:52:00","date_gmt":"2024-04-05T08:52:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=1472"},"modified":"2024-04-06T03:54:30","modified_gmt":"2024-04-06T03:54:30","slug":"hospital-de-rioverde-una-realidad-a-favor-de-las-familias","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2024\/04\/05\/hospital-de-rioverde-una-realidad-a-favor-de-las-familias\/","title":{"rendered":"Hospital de Rioverde, una realidad a favor de las familias\u00a0"},"content":{"rendered":"\n<ul>\n<li><strong>Se invit\u00f3 al Presidente de M\u00e9xico a la entrega oficial del nosocomio, que tendr\u00e1 160 camas y m\u00e1s especialistas<\/strong><\/li>\n<\/ul>\n\n\n\n<p>El Titular del Poder Ejecutivo del Estado, anunci\u00f3 que en breve se inaugurar\u00e1 el Hospital General de Rioverde, que ahora contar\u00e1 con 160 camas y m\u00e1s m\u00e9dicos especialistas, que lo consolidar\u00e1n como una nueva fortaleza en la atenci\u00f3n a la salud de las familias de toda la regi\u00f3n Media que no cuentan con derechohabiencia, por lo que ya se invit\u00f3 al Presidente de M\u00e9xico, para que lo entregue.<\/p>\n\n\n\n<p>Este nuevo nosocomio, tendr\u00e1 las mismas capacidades que el Hospital Central \u00abDr. Ignacio Morones Prieto\u00bb, en la zona metropolitana, lo que permitir\u00e1 que miles de familias de diversos municipios de la regi\u00f3n Media e incluso habitantes de otros estados, por fin puedan atender sus padecimientos y realizarse las cirug\u00edas en las nuevas instalaciones, evitando los onerosos gastos de traslados y garantizando una atenci\u00f3n digna y de calidad.<\/p>\n\n\n\n<p>Con estas nuevas instalaciones, se podr\u00e1 garantizar la atenci\u00f3n en salud a las personas de municipios como C\u00e1rdenas, Ray\u00f3n, San Ciro de Acosta, Ciudad Fern\u00e1ndez y Cerritos.<\/p>\n\n\n\n<p>Esta informaci\u00f3n es de inter\u00e9s p\u00fablico, ajena a cualquier inter\u00e9s particular o de alg\u00fan partido pol\u00edtico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Titular del Poder Ejecutivo del Estado, anunci\u00f3 que en breve se inaugurar\u00e1 el Hospital General de Rioverde, que ahora contar\u00e1 con 160 camas y m\u00e1s m\u00e9dicos especialistas, que lo consolidar\u00e1n como una nueva fortaleza en la atenci\u00f3n a la salud de las familias de toda la regi\u00f3n Media que no cuentan con derechohabiencia, por [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1473,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[3],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/1472"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=1472"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/1472\/revisions"}],"predecessor-version":[{"id":1474,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/1472\/revisions\/1474"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/1473"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=1472"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=1472"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=1472"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}