{"id":15967,"date":"2025-04-10T16:00:00","date_gmt":"2025-04-10T16:00:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=15967"},"modified":"2025-04-11T01:33:05","modified_gmt":"2025-04-11T01:33:05","slug":"canels-empresa-potosina-lider-en-exportacion-sedeco","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2025\/04\/10\/canels-empresa-potosina-lider-en-exportacion-sedeco\/","title":{"rendered":"Canel\u2019s empresa potosina l\u00edder en exportaci\u00f3n: Sedeco\u00a0"},"content":{"rendered":"\n<p><strong>\u2022&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; La empresa potosina cumple con los lineamientos del T-MEC y exporta cerca de 30 millones de d\u00f3lares anuales.<\/strong><\/p>\n\n\n\n<p>La Secretar\u00eda de Desarrollo Econ\u00f3mico (Sedeco), reconoci\u00f3 a la empresa potosina Canel&#8217;s como un referente de \u00e9xito en el \u00e1mbito de las exportaciones, destacando su identidad como Hecho en M\u00e9xico y Hecho en San Luis Potos\u00ed.<\/p>\n\n\n\n<p>El titular de la dependencia, Jes\u00fas Salvador Gonz\u00e1lez Mart\u00ednez, se\u00f1al\u00f3 que existe un respaldo real a las empresas que buscan expandirse hacia mercados internacionales, tal como lo instruy\u00f3 el Gobernador Ricardo Gallardo Cardona, brindando m\u00e1s apoyo a las y los empresarios para el desarrollo econ\u00f3mico del Estado.<\/p>\n\n\n\n<p>Con cuatro plantas de producci\u00f3n en San Luis Potos\u00ed, Canel&#8217;s fabrica productos que cumplen con altos est\u00e1ndares de calidad, as\u00ed como con las disposiciones del Tratado entre M\u00e9xico, Estados Unidos y Canad\u00e1 (T-MEC), con lo que ha consolidado una exportaci\u00f3n de 30 millones de d\u00f3lares anuales, principalmente a Estados Unidos y sus productos se distribuyen en m\u00e1s de 45 pa\u00edses de Am\u00e9rica, Europa, Asia y Medio Oriente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u2022&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; La empresa potosina cumple con los lineamientos del T-MEC y exporta cerca de 30 millones de d\u00f3lares anuales. La Secretar\u00eda de Desarrollo Econ\u00f3mico (Sedeco), reconoci\u00f3 a la empresa potosina Canel&#8217;s como un referente de \u00e9xito en el \u00e1mbito de las exportaciones, destacando su identidad como Hecho en M\u00e9xico y Hecho en San Luis Potos\u00ed. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":15968,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[3],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/15967"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=15967"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/15967\/revisions"}],"predecessor-version":[{"id":15969,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/15967\/revisions\/15969"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/15968"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=15967"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=15967"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=15967"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}