{"id":18543,"date":"2025-06-06T15:30:00","date_gmt":"2025-06-06T15:30:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=18543"},"modified":"2025-06-07T01:23:37","modified_gmt":"2025-06-07T01:23:37","slug":"gobierno-estatal-colabora-con-la-cfe-para-evitar-cortes-electricos","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2025\/06\/06\/gobierno-estatal-colabora-con-la-cfe-para-evitar-cortes-electricos\/","title":{"rendered":"Gobierno estatal colabora con la CFE para evitar cortes el\u00e9ctricos"},"content":{"rendered":"\n<p><strong>\u2022&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; El Gobernador Ricardo Gallardo se reuni\u00f3 con alcaldes y el superintendente de la Comisi\u00f3n para dar soluci\u00f3n a los cortes en el suministro en la Huasteca y el Altiplano<\/strong><\/p>\n\n\n\n<p>El Gobierno del Estado de San Luis Potos\u00ed integrar\u00e1 una agenda espec\u00edfica por zonas y municipios, con el fin de atender los cortes de energ\u00eda el\u00e9ctrica que se han registrado con mayor frecuencia en el Altiplano y la Huasteca, con el respaldo de la Comisi\u00f3n Federal de Electricidad (CFE).<\/p>\n\n\n\n<p>Lo anterior lo inform\u00f3 el secretario general de Gobierno, J. Guadalupe Torres S\u00e1nchez, quien record\u00f3 que el Gobernador Ricardo Gallardo Cardona encabez\u00f3 una reuni\u00f3n con las y los alcaldes de los 59 municipios y funcionarios federales, entre ellos el superintendente de la CFE, Jos\u00e9 \u00c1ngel Elizondo Sald\u00edvar, donde se acord\u00f3 que el funcionario federal se reunir\u00e1 con los ediles a fin de tener un informe detallado de los casos y sus causas.<\/p>\n\n\n\n<p>Torres S\u00e1nchez precis\u00f3 que en esta temporada la suspensi\u00f3n de energ\u00eda se relaciona con las lluvias que se registran en diversas regiones del Estado \u201ces un problema en el que intervienen diferentes causas, no es generalizada. El Gobernador Ricardo Gallardo propuso que la CFE y las y los alcaldes que han visto afectado sus municipios, se re\u00fanan para dar una soluci\u00f3n a cada uno de ellos\u201d; agreg\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u2022&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; El Gobernador Ricardo Gallardo se reuni\u00f3 con alcaldes y el superintendente de la Comisi\u00f3n para dar soluci\u00f3n a los cortes en el suministro en la Huasteca y el Altiplano El Gobierno del Estado de San Luis Potos\u00ed integrar\u00e1 una agenda espec\u00edfica por zonas y municipios, con el fin de atender los cortes de energ\u00eda [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":18544,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[3],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/18543"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=18543"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/18543\/revisions"}],"predecessor-version":[{"id":18545,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/18543\/revisions\/18545"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/18544"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=18543"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=18543"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=18543"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}