{"id":1868,"date":"2024-04-13T13:42:00","date_gmt":"2024-04-13T13:42:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=1868"},"modified":"2024-04-13T20:16:05","modified_gmt":"2024-04-13T20:16:05","slug":"mas-de-200-obras-para-atender-sequia","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2024\/04\/13\/mas-de-200-obras-para-atender-sequia\/","title":{"rendered":"M\u00e1s de 200 obras para atender sequ\u00eda\u00a0"},"content":{"rendered":"\n<p>Se han impulsado 208 obras de reparaci\u00f3n y construcci\u00f3n de bordos de abrevadero y represas, con lo que se prev\u00e9 el almacenamiento de agua de lluvia y se atienden los efectos derivados de la sequ\u00eda de los \u00faltimos 10 a\u00f1os en el campo potosino.&nbsp;<\/p>\n\n\n\n<p>Se inform\u00f3 que desde el 2023 y lo que va de 2024 se han entregado 156 obras del Programa de Construcci\u00f3n de Bordos de Abrevadero, as\u00ed como otras 52 represas m\u00e1s en las cuatro regiones para beneficiar a m\u00e1s de 20 mil familias productoras.<\/p>\n\n\n\n<p>Este programa se ha impulsado en coordinaci\u00f3n con los ayuntamientos y productores, y se pone a disposici\u00f3n ocho m\u00e1quinas tipo Bulldozer D-6 y la mano de obra, a fin de que las y los productores de ganado y de cultivos agr\u00edcolas no parezcan los estragos de la sequ\u00eda.<\/p>\n\n\n\n<p>Esta informaci\u00f3n es de inter\u00e9s p\u00fablico, ajena a cualquier partido pol\u00edtico o de promoci\u00f3n personal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se han impulsado 208 obras de reparaci\u00f3n y construcci\u00f3n de bordos de abrevadero y represas, con lo que se prev\u00e9 el almacenamiento de agua de lluvia y se atienden los efectos derivados de la sequ\u00eda de los \u00faltimos 10 a\u00f1os en el campo potosino.&nbsp; Se inform\u00f3 que desde el 2023 y lo que va de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1869,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[3],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/1868"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=1868"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/1868\/revisions"}],"predecessor-version":[{"id":1870,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/1868\/revisions\/1870"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/1869"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=1868"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=1868"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=1868"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}