{"id":1992,"date":"2024-04-16T14:06:00","date_gmt":"2024-04-16T14:06:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=1992"},"modified":"2024-04-16T20:47:35","modified_gmt":"2024-04-16T20:47:35","slug":"ceepac-determina-financiamiento-para-campana-de-candidaturas-independientes","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2024\/04\/16\/ceepac-determina-financiamiento-para-campana-de-candidaturas-independientes\/","title":{"rendered":"CEEPAC determina financiamiento para campa\u00f1a de candidaturas independientes"},"content":{"rendered":"\n<ul>\n<li><strong>Se establecieron tambi\u00e9n los l\u00edmites de aportaciones de simpatizantes y aportaciones individuales para las candidaturas independientes.<\/strong><\/li>\n<\/ul>\n\n\n\n<p>En sesi\u00f3n ordinaria del Consejo General del Consejo Estatal Electoral y de Participaci\u00f3n Ciudadana (CEEPAC), se determin\u00f3 la distribuci\u00f3n del financiamiento p\u00fablico para la campa\u00f1a electoral de las candidaturas independientes, as\u00ed como los l\u00edmites del financiamiento privado del Proceso Electoral Local 2024, para estas candidaturas.<\/p>\n\n\n\n<p>La normatividad electoral precisa que las candidatas y candidatos independientes tendr\u00e1n derecho a recibir financiamiento p\u00fablico para sus gastos de campa\u00f1a. Cabe se\u00f1alar que para los efectos de la distribuci\u00f3n del financiamiento p\u00fablico y prerrogativas a que tienen derecho las candidaturas Independientes deben ser considerados como un partido pol\u00edtico de nuevo registro.<\/p>\n\n\n\n<p>En ese sentido, el monto que le corresponder\u00eda a un partido de nuevo registro se distribuir\u00e1 entre los tres tipos de elecci\u00f3n correspondiendo un 33.3% a cada uno.<\/p>\n\n\n\n<p>El porcentaje del 33.3% para Ayuntamientos es de 987,725.06 pesos y 33.3% para las candidaturas independientes de diputaciones es de 987, 725.06 pesos; haciendo un total de 1, 975, 450.12 pesos.<\/p>\n\n\n\n<p>Se debe destacar que en el Proceso Electoral 2024 en San Luis Potos\u00ed, \u00fanicamente se cuenta con la procedencia de las candidaturas de Ayuntamientos, debido a que las y los aspirantes de diputaciones no reunieron el porcentaje m\u00ednimo de apoyo ciudadano que es el 2% de la lista nominal de electores.&nbsp;&nbsp;<\/p>\n\n\n\n<p>Por lo que, de acuerdo al art\u00edculo 237 de la LEE, la campa\u00f1a de las diputaciones no se utilizar\u00e1, ni se distribuir\u00e1 entre los partidos pol\u00edticos que participen en el Proceso Electoral.<\/p>\n\n\n\n<p>El recurso por la suma de 987,725.06 pesos se distribuir\u00e1 entre las cuatro candidaturas independientes, los cuales recibir\u00e1n la cantidad de 246,931.26 pesos cada independiente para la realizaci\u00f3n de sus campa\u00f1as.<\/p>\n\n\n\n<p>Las y los candidatos independientes quienes obtuvieron la declaratoria de procedencia y que obtendr\u00e1n los recursos para contender son:<\/p>\n\n\n\n<p>Mar\u00eda Elia Rodr\u00edguez Lucero de Ciudad Valles, Leonardo Vinaja V\u00e1zquez de Mexquitic de Carmona Carlos Dur\u00e1n Trejo de Xilitla y Rafael Olvera Torres de El Naranjo.<\/p>\n\n\n\n<p>El financiamiento p\u00fablico, la definici\u00f3n de topes de gasto de campa\u00f1a y de financiamiento\u00a0 privado para la elecci\u00f3n de ayuntamiento de las candidaturas independientes queda de la siguiente forma:<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"345\" src=\"https:\/\/smnoticias.com.mx\/wp-content\/uploads\/2024\/04\/gastos-ceepac.jpg\" alt=\"\" class=\"wp-image-1994\" srcset=\"https:\/\/smnoticias.com.mx\/wp-content\/uploads\/2024\/04\/gastos-ceepac.jpg 800w, https:\/\/smnoticias.com.mx\/wp-content\/uploads\/2024\/04\/gastos-ceepac-300x129.jpg 300w, https:\/\/smnoticias.com.mx\/wp-content\/uploads\/2024\/04\/gastos-ceepac-768x331.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p>Por lo respecta al l\u00edmite individual de aportaciones de simpatizantes, en dinero o en especie, se estableci\u00f3 la cantidad de 146,119.32 pesos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En sesi\u00f3n ordinaria del Consejo General del Consejo Estatal Electoral y de Participaci\u00f3n Ciudadana (CEEPAC), se determin\u00f3 la distribuci\u00f3n del financiamiento p\u00fablico para la campa\u00f1a electoral de las candidaturas independientes, as\u00ed como los l\u00edmites del financiamiento privado del Proceso Electoral Local 2024, para estas candidaturas. La normatividad electoral precisa que las candidatas y candidatos independientes [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1993,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[13],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/1992"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=1992"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/1992\/revisions"}],"predecessor-version":[{"id":1995,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/1992\/revisions\/1995"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/1993"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=1992"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=1992"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=1992"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}