{"id":2337,"date":"2024-04-22T13:30:00","date_gmt":"2024-04-22T13:30:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=2337"},"modified":"2024-04-22T21:52:19","modified_gmt":"2024-04-22T21:52:19","slug":"soledad-de-gs-arranca-modernizacion-de-andadores-y-caminamientos-en-colonia-san-antonio","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2024\/04\/22\/soledad-de-gs-arranca-modernizacion-de-andadores-y-caminamientos-en-colonia-san-antonio\/","title":{"rendered":"Soledad de GS arranca modernizaci\u00f3n de andadores y caminamientos en colonia San Antonio"},"content":{"rendered":"\n<ul>\n<li><strong>Tendr\u00e1 una inversi\u00f3n superior a los cinco millones de pesos y ser\u00e1 beneficio directo para miles habitantes directos e indirectos.<\/strong><\/li>\n<\/ul>\n\n\n\n<p>Con el prop\u00f3sito de elevar la plusval\u00eda de la zona y mejorar la calidad de vida de habitantes, este lunes en &nbsp;Soledad de Graciano S\u00e1nchez, &nbsp;se dio inicio a la obra de modernizaci\u00f3n de andadores y caminamientos en las Plazas Plutarco El\u00edas Calles de la colonia San Antonio.<\/p>\n\n\n\n<p>Estos trabajos representan un paso fundamental para dejar atr\u00e1s las irregularidades de los obsoletos andadores y servicios, con una inversi\u00f3n superior a los cinco millones de pesos, aportando un beneficio a aproximadamente ocho mil habitantes directos e indirectos de la zona.<\/p>\n\n\n\n<p>La superficie a intervenir abarca aproximadamente 25 mil 381 metros cuadrados, donde se realizar\u00e1n trabajos de zanjas hidr\u00e1ulicas y sanitarias para instalar tuber\u00edas nuevas, con las pruebas hidrosanitarias necesarias para asegurar una ejecuci\u00f3n correcta y duradera. Asimismo, se retirar\u00e1 el pavimento actual, el cual ser\u00e1 sustituido por concreto estampado, contribuyendo as\u00ed a mejorar la armon\u00eda y la calidad est\u00e9tica de los espacios.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con el prop\u00f3sito de elevar la plusval\u00eda de la zona y mejorar la calidad de vida de habitantes, este lunes en &nbsp;Soledad de Graciano S\u00e1nchez, &nbsp;se dio inicio a la obra de modernizaci\u00f3n de andadores y caminamientos en las Plazas Plutarco El\u00edas Calles de la colonia San Antonio. Estos trabajos representan un paso fundamental para [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2338,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[10],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/2337"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=2337"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/2337\/revisions"}],"predecessor-version":[{"id":2339,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/2337\/revisions\/2339"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/2338"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=2337"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=2337"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=2337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}