{"id":23440,"date":"2025-10-01T14:12:00","date_gmt":"2025-10-01T14:12:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=23440"},"modified":"2025-10-02T00:27:02","modified_gmt":"2025-10-02T00:27:02","slug":"sege-exhorta-a-escuelas-privadas-a-fortalecer-protocolos-de-seguridad-escolar","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2025\/10\/01\/sege-exhorta-a-escuelas-privadas-a-fortalecer-protocolos-de-seguridad-escolar\/","title":{"rendered":"SEGE exhorta a escuelas privadas a fortalecer protocolos de seguridad escolar"},"content":{"rendered":"\n<p><strong>\u2022&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Indispensable que las instituciones privadas refuercen la aplicaci\u00f3n y capacitaci\u00f3n de los Protocolos de Seguridad Escolar de la Secretar\u00eda de Educaci\u00f3n.<\/strong><\/p>\n\n\n\n<p>La Secretar\u00eda de Educaci\u00f3n de Gobierno del Estado (SEGE) informa que derivado de una denuncia ciudadana que, involucra a la escuela privada Instituto \u00abSalesiano\u00bb Carlos G\u00f3mez, la dependencia solicit\u00f3 informaci\u00f3n a los directivos de esta escuela, a fin de garantizar la seguridad e integridad de las y los alumnos potosinos inscritos, quienes indicaron que se llev\u00f3 a cabo la aplicaci\u00f3n de los Protocolos de Seguridad.<\/p>\n\n\n\n<p>Es importante mencionar que esta instituci\u00f3n educativa en sus distintos niveles se encuentra incorporado al Sistema Educativo Estatal Regular (SEER) para la atenci\u00f3n en educaci\u00f3n b\u00e1sica, a la Universidad Aut\u00f3noma de San Luis Potos\u00ed (UASLP) en el bachillerato universitario y al Centro de Bachillerato Tecnol\u00f3gico Industrial y de Servicios (Cbtis) en el bachillerato tecnol\u00f3gico; sin embargo, la SEGE act\u00faa privilegiando el inter\u00e9s superior a la educaci\u00f3n de las y los ni\u00f1os y j\u00f3venes potosinos.<\/p>\n\n\n\n<p>La SEGE entabl\u00f3 comunicaci\u00f3n con la Secretar\u00eda de Seguridad y Protecci\u00f3n Ciudadana, gracias a los convenios de colaboraci\u00f3n con la misma, la cual inform\u00f3 que, la Guardia Civil Estatal acudi\u00f3 y entrevist\u00f3 a las autoridades educativas del plantel, verificando que la escuela est\u00e1 en orden y calma.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u2022&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Indispensable que las instituciones privadas refuercen la aplicaci\u00f3n y capacitaci\u00f3n de los Protocolos de Seguridad Escolar de la Secretar\u00eda de Educaci\u00f3n. La Secretar\u00eda de Educaci\u00f3n de Gobierno del Estado (SEGE) informa que derivado de una denuncia ciudadana que, involucra a la escuela privada Instituto \u00abSalesiano\u00bb Carlos G\u00f3mez, la dependencia solicit\u00f3 informaci\u00f3n a los directivos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":23441,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[3],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/23440"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=23440"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/23440\/revisions"}],"predecessor-version":[{"id":23442,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/23440\/revisions\/23442"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/23441"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=23440"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=23440"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=23440"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}