{"id":235,"date":"2024-03-04T11:31:00","date_gmt":"2024-03-04T11:31:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=235"},"modified":"2024-03-05T04:34:51","modified_gmt":"2024-03-05T04:34:51","slug":"potosinos-celebran-dia-de-la-familia-en-parques-tangamanga-y-las-camelias","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2024\/03\/04\/potosinos-celebran-dia-de-la-familia-en-parques-tangamanga-y-las-camelias\/","title":{"rendered":"Potosinos celebran D\u00eda de la Familia en parques Tangamanga y las Camelias"},"content":{"rendered":"\n<ul>\n<li><strong>Personas de todas las edades disfrutaron de las amenidades e instalaciones con actividades recreativas y momentos especiales en compa\u00f1\u00eda de sus seres queridos<\/strong><\/li>\n<\/ul>\n\n\n\n<p>Este domingo 3 de marzo, en medio de alegr\u00eda y convivencia, las y los potosinos acudieron a los parques Tangamanga I y II y Las Camelias de Matehuala, para celebrar el \u201cD\u00eda Nacional de la Familia\u201d, con afluencia de personas de todas las edades, quienes disfrutaron de las amenidades e instalaciones, con actividades recreativas y momentos especiales en compa\u00f1\u00eda de sus seres queridos.<\/p>\n\n\n\n<p>Con gran afluencia, las diversas \u00e1reas de los parques, ofrecieron espacios para la diversi\u00f3n y el entretenimiento, desde juegos sanos y competitivos hasta los tradicionales paseos en el \u201cTrenecito\u201d, caminatas, picnic bajo la sombra de los \u00e1rboles, y con especial inter\u00e9s en el Parque Japon\u00e9s, que con sus instalaciones destac\u00f3 como uno de los puntos m\u00e1s atractivos, con la experiencia de sumergirse en la cultura milenaria del Jap\u00f3n.<\/p>\n\n\n\n<p>El Poder Ejecutivo del Estado, a trav\u00e9s de la administraci\u00f3n de los Centros de Recreaci\u00f3n, felicit\u00f3 a las y los potosinos por este d\u00eda, y los invit\u00f3 para que contin\u00faen asistiendo a los parques Tangamanga, y Las Camelias a disfrutar de sus instalaciones en los horarios: el lunes de 05:00 a 11:00 horas con \u00faltimo acceso a las 10:30; de martes a s\u00e1bado de 05:00 a 22:30 horas con \u00faltimo acceso a las 21:30 horas y el domingo de 05:00 a 18:00 horas con \u00faltimo acceso a las 17:00.&nbsp;<\/p>\n\n\n\n<p>Esta actividad es de inter\u00e9s p\u00fablico, de car\u00e1cter informativo, ajena a cualquier inter\u00e9s particular o alg\u00fan partido pol\u00edtico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este domingo 3 de marzo, en medio de alegr\u00eda y convivencia, las y los potosinos acudieron a los parques Tangamanga I y II y Las Camelias de Matehuala, para celebrar el \u201cD\u00eda Nacional de la Familia\u201d, con afluencia de personas de todas las edades, quienes disfrutaron de las amenidades e instalaciones, con actividades recreativas y [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":236,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[3],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/235"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=235"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/235\/revisions"}],"predecessor-version":[{"id":237,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/235\/revisions\/237"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/236"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=235"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=235"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=235"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}