{"id":23802,"date":"2025-10-10T19:29:00","date_gmt":"2025-10-10T19:29:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=23802"},"modified":"2025-10-10T23:31:23","modified_gmt":"2025-10-10T23:31:23","slug":"ceepac-aprueba-presupuesto-para-el-ejercicio-fiscal-2026","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2025\/10\/10\/ceepac-aprueba-presupuesto-para-el-ejercicio-fiscal-2026\/","title":{"rendered":"CEEPAC aprueba presupuesto para el ejercicio fiscal 2026"},"content":{"rendered":"\n<p><strong>*El presupuesto responde a las necesidades y actividades establecidas en la normatividad del estado.<\/strong><\/p>\n\n\n\n<p><strong>*Se aprob\u00f3 financiamiento p\u00fablico para partidos pol\u00edticos registrados para 2026<\/strong><\/p>\n\n\n\n<p>El Consejo General del Consejo Estatal Electoral y de Participaci\u00f3n Ciudadana (CEEPAC), aprob\u00f3 el Proyecto de Presupuesto de Egresos para el ejercicio fiscal 2026, que ser\u00e1 enviado a la Secretar\u00eda de Finanzas para su inclusi\u00f3n en el Proyecto de Ley de Presupuesto de Egresos del Estado.<\/p>\n\n\n\n<p>En su intervenci\u00f3n, la consejera electoral Graciela D\u00edaz V\u00e1zquez se\u00f1al\u00f3 que, \u201cEn 2027 habr\u00e1 elecciones por lo que es indispensable que se cuente con recursos y suficiencia presupuestal en 2026 para los preparativos de inicio del proceso electoral\u201d.<\/p>\n\n\n\n<p>El presupuesto total solicitado para el ejercicio fiscal del organismo electoral en 2026 es de 233 millones, 552 mil, 222.86 pesos.<\/p>\n\n\n\n<p>Este monto est\u00e1 compuesto por los siguientes rubros necesarios para la operatividad del organismo electoral:<\/p>\n\n\n\n<p>\u2022&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Gasto ordinario por la cantidad de 97 millones, 915 mil, 741.27 pesos;<\/p>\n\n\n\n<p>\u2022&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Inicio de proceso electoral por 77 millones, 938 mil, 377.21 pesos;<\/p>\n\n\n\n<p>\u2022&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Proyectos transversales por 662 mil pesos.<\/p>\n\n\n\n<p>\u2022&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Pasivos contingentes por 40 millones, 606 mil, 653.47 pesos;<\/p>\n\n\n\n<p>\u2022&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Pasivos convenio INE por 16 millones, 429 mil, 450.91 pesos.<\/p>\n\n\n\n<p>Durante la sesi\u00f3n tambi\u00e9n se determin\u00f3 el presupuesto para el financiamiento p\u00fablico de los partidos pol\u00edticos registrados o inscritos ante el organismo electoral para el ejercicio fiscal 2026 en la que se aprob\u00f3 la cantidad total de $174 millones, 215 mil, 596.28 pesos.<\/p>\n\n\n\n<p>Este financiamiento a partidos pol\u00edticos est\u00e1 compuesto de cuatro segmentos:<\/p>\n\n\n\n<p>\u2022&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Sostenimiento de actividades ordinarias permanentes por 165 millones, 811 mil, 863.13 pesos;<\/p>\n\n\n\n<p>\u2022&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Actividades espec\u00edficas por 4 millones, 974 mil, 355.89 pesos;<\/p>\n\n\n\n<p>\u2022&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Franquicia postal y telegr\u00e1fica por 3 millones, 316 mil, 237.26 pesos;<\/p>\n\n\n\n<p>\u2022&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Y financiamiento adicional a partidos pol\u00edticos locales de proceso electoral por 113 mil, 114.00 pesos.<\/p>\n\n\n\n<p>Es importante se\u00f1alar que de los rubros se\u00f1alados el 30% se distribuye de forma igualitaria entre todos los partidos pol\u00edticos, y el 70% se distribuye de acuerdo al porcentaje de votos que se obtuvieron en la elecci\u00f3n de diputaciones, inmediata anterior.<\/p>\n\n\n\n<p>En otro punto del orden del d\u00eda el Consejo General del CEEPAC, aprob\u00f3 la integraci\u00f3n de las comisiones permanentes para el ejercicio que inicia el d\u00eda 15 de octubre de 2025 y que concluir\u00e1 el 14 de octubre del 2026, quedando integradas de la siguiente manera:<\/p>\n\n\n\n<p>\u2022&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Comisi\u00f3n de fiscalizaci\u00f3n, integrada por las consejer\u00edas: Gerardo Lomel\u00ed Rodr\u00edguez, Karla Patricia Sol\u00eds Dibildox y Juan Manuel Ram\u00edrez Garc\u00eda.<\/p>\n\n\n\n<p>\u2022&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Comisi\u00f3n de capacitaci\u00f3n electoral, educaci\u00f3n c\u00edvica y cultura pol\u00edtica organizaci\u00f3n electoral integrada por las consejer\u00edas: \u00d3scar Felipe Reyna Jim\u00e9nez, Paloma Blanco L\u00f3pez&nbsp; y Carlos David Cu\u00e9llar Arochi.<\/p>\n\n\n\n<p>\u2022&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Comisi\u00f3n de organizaci\u00f3n electoral, integrada por: Juan Manuel Ram\u00edrez Garc\u00eda,&nbsp; Graciela D\u00edaz V\u00e1zquez y \u00d3scar Felipe Reyna Jim\u00e9nez.<\/p>\n\n\n\n<p>\u2022&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Comisi\u00f3n de prerrogativas y partidos pol\u00edticos, integrada por : Juan Manuel Ram\u00edrez Garc\u00eda, Luis Gerardo Lomel\u00ed Rodr\u00edguez y Paloma Blanco L\u00f3pez.<\/p>\n\n\n\n<p>\u2022&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Comisi\u00f3n de administraci\u00f3n integrada por:&nbsp; Karla Patricia Sol\u00eds Dibildox , Carlos David Cu\u00e9llar Arochi y Graciela D\u00edaz V\u00e1zquez.<\/p>\n\n\n\n<p>\u2022&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Comisi\u00f3n de&nbsp; quejas y denuncias, integrada por: Carlos David Cu\u00e9llar Arochi,&nbsp; Luis Gerardo Lomel\u00ed Rodr\u00edguez y Karla Patricia Sol\u00eds Dibildox<\/p>\n\n\n\n<p>\u2022&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Comisi\u00f3n de seguimiento al servicio profesional electoral integrada por: Paloma Blanco L\u00f3pez,&nbsp; \u00d3scar Felipe Reyna Jim\u00e9nez y Carlos David Cu\u00e9llar Arochi.<\/p>\n\n\n\n<p>\u2022&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; La comisi\u00f3n de g\u00e9nero e inclusi\u00f3n integrada por las consejer\u00edas:&nbsp; Paloma Blanco L\u00f3pez,&nbsp; Graciela D\u00edaz V\u00e1zquez y Carlos David Cu\u00e9llar Arochi.<\/p>\n\n\n\n<p>Adem\u00e1s, se aprob\u00f3 la creaci\u00f3n de la Comisi\u00f3n Temporal para la elaboraci\u00f3n de las observaciones a la Legislaci\u00f3n Electoral con base en las experiencias derivadas del Proceso Electoral Local Extraordinario 2025, se integrar\u00e1 con las siguientes Consejer\u00edas Electorales:&nbsp; Graciela D\u00edaz V\u00e1zquez, Juan Manuel Ram\u00edrez Garc\u00eda, Karla Patricia Sol\u00eds Dibildox, \u00d3scar Felipe Reyna Jim\u00e9nez y Luis Gerardo Lomel\u00ed Rodr\u00edguez.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>*El presupuesto responde a las necesidades y actividades establecidas en la normatividad del estado. *Se aprob\u00f3 financiamiento p\u00fablico para partidos pol\u00edticos registrados para 2026 El Consejo General del Consejo Estatal Electoral y de Participaci\u00f3n Ciudadana (CEEPAC), aprob\u00f3 el Proyecto de Presupuesto de Egresos para el ejercicio fiscal 2026, que ser\u00e1 enviado a la Secretar\u00eda de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":23803,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[13],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/23802"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=23802"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/23802\/revisions"}],"predecessor-version":[{"id":23804,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/23802\/revisions\/23804"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/23803"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=23802"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=23802"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=23802"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}