{"id":24436,"date":"2025-10-28T10:12:00","date_gmt":"2025-10-28T10:12:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=24436"},"modified":"2025-10-28T16:38:34","modified_gmt":"2025-10-28T16:38:34","slug":"grandes-emociones-este-martes-en-los-xii-juegos-latinoamericanos-de-policias-y-bomberos-2025-san-luis-capital","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2025\/10\/28\/grandes-emociones-este-martes-en-los-xii-juegos-latinoamericanos-de-policias-y-bomberos-2025-san-luis-capital\/","title":{"rendered":"Grandes emociones este martes, en los XII Juegos Latinoamericanos de Polic\u00edas y Bomberos 2025 &#8211; San Luis Capital"},"content":{"rendered":"\n<ul>\n<li><strong>San Luis Potos\u00ed es el epicentro deportivo de Latinoam\u00e9rica, recibiendo a polic\u00edas y bomberos en una emocionante justa de compa\u00f1erismo y alto rendimiento.<\/strong><\/li>\n<\/ul>\n\n\n\n<p>San Luis Potos\u00ed, como sede de los XII Juegos Latinoamericanos de Polic\u00edas y Bomberos en 2025, re\u00fane a atletas de toda la regi\u00f3n en una competencia de alto nivel. El programa de actividades para el martes 28 de octubre de 2025 destaca una amplia gama de disciplinas deportivas que se llevar\u00e1n a cabo en diversas sedes de la Capital.<\/p>\n\n\n\n<p>Desde las 8:00 H, los participantes podr\u00e1n disfrutar de emocionantes encuentros de F\u00fatbol 5 en el Centro Deportivo Topacio, Voleibol en Plaza Aranzaz\u00fa, Tiro FBI en Acr\u00f3polis, y Baloncesto en la Unidad Deportiva Universitaria Colorines. Simult\u00e1neamente, el Softbol se disputar\u00e1 en el Centro Deportivo Garita.<\/p>\n\n\n\n<p>M\u00e1s tarde, a las 9:00 H, el Frontenis tendr\u00e1 lugar en el Club Liban\u00e9s Potosino, el Powerlifting en Plaza de Armas y el Tenis de Mesa en la Unidad Administrativa Municipal. La jornada deportiva culminar\u00e1 con Box a las 12:00 H en Plaza de Armas.<\/p>\n\n\n\n<p>La jornada del 28 de octubre cerrar\u00e1 con broche de oro con la Ceremonia de Medallas, programada para las 19:00 H en el Palacio Municipal, donde se reconocer\u00e1 el esfuerzo y la dedicaci\u00f3n de los atletas. Este evento, organizado por el Gobierno de la Capital, busca fomentar la sana competencia y el compa\u00f1erismo entre los cuerpos de seguridad y emergencia de Latinoam\u00e9rica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>San Luis Potos\u00ed, como sede de los XII Juegos Latinoamericanos de Polic\u00edas y Bomberos en 2025, re\u00fane a atletas de toda la regi\u00f3n en una competencia de alto nivel. El programa de actividades para el martes 28 de octubre de 2025 destaca una amplia gama de disciplinas deportivas que se llevar\u00e1n a cabo en diversas [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":24437,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[4],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/24436"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=24436"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/24436\/revisions"}],"predecessor-version":[{"id":24438,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/24436\/revisions\/24438"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/24437"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=24436"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=24436"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=24436"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}