{"id":25695,"date":"2025-11-25T13:55:00","date_gmt":"2025-11-25T13:55:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=25695"},"modified":"2025-11-25T23:16:12","modified_gmt":"2025-11-25T23:16:12","slug":"en-el-25n-alcalde-navarro-muniz-apertura-el-primer-centro-libre-para-proteger-de-la-violencia-a-mujeres-ninas-y-adolescentes","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2025\/11\/25\/en-el-25n-alcalde-navarro-muniz-apertura-el-primer-centro-libre-para-proteger-de-la-violencia-a-mujeres-ninas-y-adolescentes\/","title":{"rendered":"En el 25N, alcalde Navarro Mu\u00f1iz apertura el primer Centro Libre para Proteger de la Violencia a Mujeres, Ni\u00f1as y Adolescentes"},"content":{"rendered":"\n<p><strong>&#8211; En el D\u00eda Internacional de la Erradicaci\u00f3n de la Violencia contra las Mujeres, el Alcalde entreg\u00f3 en la colonia Pav\u00f3n este refugio, creado como parte de las pol\u00edticas de rescate de espacios p\u00fablicos, construido con recursos municipales.<\/strong><\/p>\n\n\n\n<p><strong>&#8211; La Secretar\u00eda de Mujeres en el Estado afirm\u00f3 que este Centro es el modelo de la infraestructura que se pide replicar en todo el Estado, por lo que respald\u00f3 y reconoci\u00f3 la visi\u00f3n del Alcalde.<\/strong><\/p>\n\n\n\n<p>En un d\u00eda de gran significado social, como es el 25N, D\u00eda Internacional de la Erradicaci\u00f3n de la Violencia contra las Mujeres, Juan Manuel Navarro Mu\u00f1iz, Alcalde de Soledad de Graciano S\u00e1nchez, cort\u00f3 el list\u00f3n inaugural del primer Centro LIBRE en la demarcaci\u00f3n, un espacio cuyo nombre representa sus principios fundamentales: Libertad, Igualdad, Bienestar, Redes y Emancipaci\u00f3n, y posiciona nuevamente al municipio como referente en acciones para proteger, impulsar y atender a mujeres de todas las edades contra actos de violencia.<\/p>\n\n\n\n<p>Con una inversi\u00f3n de casi dos millones de pesos&nbsp;provenientes de recursos municipales, el nuevo espacio,&nbsp;construido en la colonia Pav\u00f3n, consolida la visi\u00f3n&nbsp;de cercan\u00eda, atenci\u00f3n directa y rescate de espacios p\u00fablicos para impulsar el desarrollo integral de quienes m\u00e1s requieren acompa\u00f1amiento y protecci\u00f3n; el proyecto se edific\u00f3 sobre m\u00e1s de 290 metros cuadrados y ofrece \u00e1reas de atenci\u00f3n jur\u00eddica, trabajo social, empoderamiento, psicolog\u00eda, ludoteca, capacitaci\u00f3n y zona infantil, para beneficio de m\u00e1s de seis&nbsp;mil habitantes de manera directa e indirecta.<\/p>\n\n\n\n<p>Durante su mensaje, el Alcalde destac\u00f3 que esta infraestructura representa un compromiso firme con la seguridad y el desarrollo de ni\u00f1as, adolescentes y mujeres: \u201cHoy Soledad abre las puertas de su primer Centro Libre en un d\u00eda simb\u00f3lico que nos llama a reflexionar y actuar, no es una fecha cualquiera, es una conmemoraci\u00f3n que nos compromete a trabajar todos los d\u00edas para erradicar la violencia contra las mujeres, queremos un municipio donde cada d\u00eda sea un d\u00eda libre de violencia\u201d.<\/p>\n\n\n\n<p>El Alcalde resalt\u00f3 que el nuevo Centro representa un doble beneficio para la colonia Pav\u00f3n: marca una ampliaci\u00f3n hist\u00f3rica en los servicios de apoyo a las mujeres y rescata un espacio que hab\u00eda perdido utilidad y generaba riesgos. A\u00f1adi\u00f3 que, gracias a la apertura y el respaldo del Gobernador, Ricardo Gallardo Cardona, Soledad impulsa proyectos que lo posicionan al frente del resto de&nbsp;municipios con infraestructura social de verdadero sentido humano, lo que eleva el compromiso de mantener a Soledad como el municipio n\u00famero uno en iniciativas que priorizan a los sectores m\u00e1s vulnerables.<\/p>\n\n\n\n<p>La titular de la Secretar\u00eda de las Mujeres en el Estado, Gloria Serrato S\u00e1nchez&nbsp;destac\u00f3 que Soledad se convierte hoy en el modelo estatal de estos Centros Libre, gracias al respaldo decidido del Gobierno Municipal. \u201cEstamos muy contentas de lanzar desde Soledad el prototipo de lo que queremos replicar en todo el estado, este espacio es posible por la gesti\u00f3n del Gobernador Ricardo Gallardo y por el apoyo del Presidente municipal, Juan Manuel Navarro Mu\u00f1iz, quien no brind\u00f3 \u00fanicamente un lugar digno, sino que construy\u00f3 uno nuevo y totalmente equipado; aqu\u00ed las mujeres encontrar\u00e1n abogadas, psic\u00f3logas, trabajadoras sociales y acompa\u00f1amiento humano especializado\u201d, se\u00f1al\u00f3.<\/p>\n\n\n\n<p>Serrato S\u00e1nchez subray\u00f3 que este Centro representa un mensaje de esperanza, seguridad y autonom\u00eda para todas las mujeres de la regi\u00f3n y reconoci\u00f3 que la recuperaci\u00f3n de este espacio simboliza el compromiso del municipio con la tranquilidad, el bienestar y la libertad de las mujeres soledenses. \u201cEs tiempo de mujeres, es tiempo de vivir libres de violencia\u201d, afirm\u00f3 al invitar a las vecinas a aprovechar los talleres, servicios, capacitaciones y recursos que desde hoy estar\u00e1n al alcance de todas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8211; En el D\u00eda Internacional de la Erradicaci\u00f3n de la Violencia contra las Mujeres, el Alcalde entreg\u00f3 en la colonia Pav\u00f3n este refugio, creado como parte de las pol\u00edticas de rescate de espacios p\u00fablicos, construido con recursos municipales. &#8211; La Secretar\u00eda de Mujeres en el Estado afirm\u00f3 que este Centro es el modelo de la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":25696,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[10],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/25695"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=25695"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/25695\/revisions"}],"predecessor-version":[{"id":25697,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/25695\/revisions\/25697"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/25696"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=25695"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=25695"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=25695"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}