{"id":25735,"date":"2025-11-26T12:49:00","date_gmt":"2025-11-26T12:49:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=25735"},"modified":"2025-11-26T21:00:21","modified_gmt":"2025-11-26T21:00:21","slug":"villa-de-pozos-fortalece-la-inclusion-de-personas-con-discapacidad","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2025\/11\/26\/villa-de-pozos-fortalece-la-inclusion-de-personas-con-discapacidad\/","title":{"rendered":"Villa de Pozos fortalece la inclusi\u00f3n de personas con discapacidad"},"content":{"rendered":"\n<ul>\n<li><strong>Durante la conferencia Movimiento de Personas con Discapacidad, autoridades municipales y ciudadan\u00eda compartieron experiencias y necesidades para avanzar hacia un municipio m\u00e1s justo.<\/strong><\/li>\n<\/ul>\n\n\n\n<p>Con el compromiso de construir un municipio verdaderamente incluyente, la Presidenta Concejal Patricia Aradillas Aradillas, quien encabeza el Gobierno Municipal de Villa de Pozos, reafirm\u00f3 su respaldo a las personas con discapacidad durante su participaci\u00f3n en la conferencia Movimiento de Personas con Discapacidad, en este espacio, integrantes del sector tuvieron la oportunidad de dialogar, expresar inquietudes y compartir experiencias directamente con autoridades municipales.<\/p>\n\n\n\n<p>La funcionaria reconoci\u00f3 la importancia de fortalecer las acciones que promuevan la dignidad, el respeto y la protecci\u00f3n de los derechos de las personas con discapacidad en la localidad y se\u00f1al\u00f3 que el Gobierno Municipal mantiene firme el compromiso de escuchar, abrir espacios de di\u00e1logo y trabajar para eliminar las barreras que a\u00fan enfrentan.<\/p>\n\n\n\n<p>Aradillas Aradillas reafirm\u00f3 que desde su administraci\u00f3n se continuar\u00e1 impulsando pol\u00edticas p\u00fablicas integrales en beneficio de todas y todos los habitantes de Villa de Pozos, para garantizar condiciones que respeten la dignidad, la igualdad de oportunidades y la plena inclusi\u00f3n de las personas con discapacidad.<\/p>\n\n\n\n<p>Durante la conferencia, Isis Libertad Lara, integrante del Movimiento de Personas con Discapacidad destac\u00f3 la relevancia de fortalecer la identidad y visibilizar las necesidades espec\u00edficas de este sector. Adem\u00e1s, anunci\u00f3 el programa de actividades a realizar el 30 de noviembre las cuales comenzar\u00e1n con una misa a las 08:00 horas en la Iglesia de Tequisquiapan, a las 09:30 horas una marcha pacifica en el Jard\u00edn de Tequisquiapan y de 09:00 a 13:00 horas se instalar\u00e1 un mercadito inclusivo y una exposici\u00f3n de pintura y arte pl\u00e1stico en el Jard\u00edn de Tequisquiapan.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con el compromiso de construir un municipio verdaderamente incluyente, la Presidenta Concejal Patricia Aradillas Aradillas, quien encabeza el Gobierno Municipal de Villa de Pozos, reafirm\u00f3 su respaldo a las personas con discapacidad durante su participaci\u00f3n en la conferencia Movimiento de Personas con Discapacidad, en este espacio, integrantes del sector tuvieron la oportunidad de dialogar, expresar [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":25736,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/25735"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=25735"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/25735\/revisions"}],"predecessor-version":[{"id":25737,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/25735\/revisions\/25737"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/25736"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=25735"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=25735"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=25735"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}