{"id":26029,"date":"2025-12-02T16:24:00","date_gmt":"2025-12-02T16:24:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=26029"},"modified":"2025-12-03T04:30:07","modified_gmt":"2025-12-03T04:30:07","slug":"nuevo-atlas-electoral-del-ceepac-fortalece-la-memoria-democratica-de-slp","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2025\/12\/02\/nuevo-atlas-electoral-del-ceepac-fortalece-la-memoria-democratica-de-slp\/","title":{"rendered":"Nuevo Atlas Electoral del Ceepac fortalece la memoria democr\u00e1tica de \u00a0SLP"},"content":{"rendered":"\n<p>&#8211;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <strong>CEEPAC presenta en la Feria Internacional del Libro de Guadalajara el \u201cAtlas de Informaci\u00f3n Electoral, Proceso Electoral Local Extraordinario 2025, San Luis Potos\u00ed\u201d<\/strong><\/p>\n\n\n\n<p>El Consejo Estatal Electoral y de Participaci\u00f3n Ciudadana (CEEPAC) particip\u00f3 en la Feria Internacional del Libro de Guadalajara con la presentaci\u00f3n de la obra \u201cAtlas de Informaci\u00f3n Electoral, Proceso Electoral Local Extraordinario 2025, San Luis Potos\u00ed\u201d, una publicaci\u00f3n que re\u00fane informaci\u00f3n anal\u00edtica, cartogr\u00e1fica y estad\u00edstica del proceso extraordinario celebrado en la entidad, con el objetivo de fortalecer la transparencia, la memoria institucional y la cultura democr\u00e1tica.<\/p>\n\n\n\n<p>La presentaci\u00f3n estuvo a cargo del consejero electoral Luis Gerardo Lomel\u00ed Rodr\u00edguez, autor de la publicaci\u00f3n,&nbsp; y de las y los consejeros electorales Juan Manuel Ram\u00edrez Garc\u00eda, Karla Patricia Sol\u00eds Dibildox y Oscar Felipe Reyna Jim\u00e9nez, quienes&nbsp; expusieron los hallazgos, aportes y aprendizajes derivados del ejercicio editorial. La actividad fue moderada por la consejera electoral Miriam Guadalupe Guti\u00e9rrez Mora, del Instituto Electoral y de Participaci\u00f3n Ciudadana de Jalisco.<\/p>\n\n\n\n<p>Durante la exposici\u00f3n, las consejer\u00edas del CEEPAC destacaron que este Atlas constituye una herramienta de consulta p\u00fablica que permite comprender, con datos verificables, las caracter\u00edsticas del Proceso Electoral Local Extraordinario 2025; su comportamiento territorial; la participaci\u00f3n ciudadana; as\u00ed como los retos log\u00edsticos, institucionales y normativos que implic\u00f3 su organizaci\u00f3n.<\/p>\n\n\n\n<p>Subrayaron que la elaboraci\u00f3n de este documento forma parte del compromiso del organismo electoral de promover la investigaci\u00f3n, la educaci\u00f3n c\u00edvica y la difusi\u00f3n del conocimiento especializado, a fin de que la ciudadan\u00eda, la academia, los medios de comunicaci\u00f3n y las instituciones p\u00fablicas cuenten con informaci\u00f3n clara, accesible y \u00fatil para el an\u00e1lisis de la vida democr\u00e1tica de San Luis Potos\u00ed.<\/p>\n\n\n\n<p>La presentaci\u00f3n se realiz\u00f3 el domingo 30 de noviembre a las 12:00 horas en el Stand H30 de la FIL Guadalajara, espacio en el que se comparti\u00f3 el valor de los estudios electorales y su importancia para seguir fortaleciendo procesos confiables, incluyentes y transparentes.<\/p>\n\n\n\n<p>El \u201cAtlas de Informaci\u00f3n Electoral, Proceso Electoral Local Extraordinario 2025, San Luis Potos\u00ed\u201d est\u00e1 disponible para consulta en el enlace: https:\/\/www.ceepacslp.org.mx\/ceepac\/uploads2\/files\/Atlas_extraordinario_2025.pdf<\/p>\n\n\n\n<p>Este Atlas se suma a los que se han hecho para elecciones y pasadas, los cuales se pueden consultar en el siguiente enlace:<\/p>\n\n\n\n<figure class=\"wp-block-embed\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/www.ceepacslp.org.mx\/ceepac\/nota\/id\/159\/informacion\/otras-publicaciones\n<\/div><\/figure>\n\n\n\n<p>&nbsp;El CEEPAC refrenda su compromiso con la construcci\u00f3n de una ciudadan\u00eda informada, con la rendici\u00f3n de cuentas y con la generaci\u00f3n de materiales que contribuyan a la comprensi\u00f3n del sistema electoral potosino, colocando siempre en el centro el derecho de todas las personas a participar en la vida p\u00fablica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8211;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; CEEPAC presenta en la Feria Internacional del Libro de Guadalajara el \u201cAtlas de Informaci\u00f3n Electoral, Proceso Electoral Local Extraordinario 2025, San Luis Potos\u00ed\u201d El Consejo Estatal Electoral y de Participaci\u00f3n Ciudadana (CEEPAC) particip\u00f3 en la Feria Internacional del Libro de Guadalajara con la presentaci\u00f3n de la obra \u201cAtlas de Informaci\u00f3n Electoral, Proceso Electoral Local [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":26034,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[13],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/26029"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=26029"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/26029\/revisions"}],"predecessor-version":[{"id":26035,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/26029\/revisions\/26035"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/26034"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=26029"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=26029"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=26029"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}