{"id":26249,"date":"2025-12-07T12:30:00","date_gmt":"2025-12-07T12:30:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=26249"},"modified":"2025-12-08T07:40:09","modified_gmt":"2025-12-08T07:40:09","slug":"congreso-aprueba-reforma-que-respaldara-los-derechos-del-personal-docente","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2025\/12\/07\/congreso-aprueba-reforma-que-respaldara-los-derechos-del-personal-docente\/","title":{"rendered":"Congreso aprueba reforma que respaldar\u00e1 los derechos del personal docente"},"content":{"rendered":"\n<ul>\n<li><strong>Las nuevas disposiciones legales fortalecen la certeza jur\u00eddica y el acompa\u00f1amiento institucional para maestras y maestros en San Luis Potos\u00ed.<\/strong><\/li>\n<\/ul>\n\n\n\n<p>El Gobierno del Estado, a trav\u00e9s de la Secretar\u00eda de Educaci\u00f3n (SEGE), celebra la aprobaci\u00f3n del Congreso del Estado a la iniciativa de ley que tiene como objetivo primordial proteger a las y los docentes que con vocaci\u00f3n gu\u00edan el futuro de San Luis Potos\u00ed ante denuncias falsas.<\/p>\n\n\n\n<p>Estas reformas, impulsadas por el secretario de Educaci\u00f3n Juan Carlos Torres Cedillo y la ex diputada Martha Patricia Aradillas Aradillas, as\u00ed como por la diputada Mar\u00eda Leticia V\u00e1zquez Hern\u00e1ndez presidenta de la Comisi\u00f3n Primera de Justicia y de la bancada del Partido Verde Ecologista de M\u00e9xico (PVEM), donde se establecen medidas para sancionar denuncias falsas, asegurar investigaciones objetivas y reforzar la aplicaci\u00f3n de protocolos institucionales en casos relacionados con el personal docente.<\/p>\n\n\n\n<p>Con 25 votos a favor, una abstenci\u00f3n y cero votos en contra, esta reforma marca un punto de inflexi\u00f3n en el panorama educativo potosino, consolidando un marco jur\u00eddico m\u00e1s justo y equilibrado que fortalece la confianza en las comunidades escolares, dando certeza a la labor docente.<\/p>\n\n\n\n<p>Finalmente el titular de la SEGE Juan Carlos Torres Cedillo, destac\u00f3 que esta aprobaci\u00f3n es un paso para garantizar que los centros educativos sean espacios libres de violencia para todas las y los integrantes de la comunidad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Gobierno del Estado, a trav\u00e9s de la Secretar\u00eda de Educaci\u00f3n (SEGE), celebra la aprobaci\u00f3n del Congreso del Estado a la iniciativa de ley que tiene como objetivo primordial proteger a las y los docentes que con vocaci\u00f3n gu\u00edan el futuro de San Luis Potos\u00ed ante denuncias falsas. Estas reformas, impulsadas por el secretario de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":26250,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[3],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/26249"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=26249"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/26249\/revisions"}],"predecessor-version":[{"id":26251,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/26249\/revisions\/26251"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/26250"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=26249"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=26249"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=26249"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}