{"id":26317,"date":"2025-12-09T13:30:00","date_gmt":"2025-12-09T13:30:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=26317"},"modified":"2025-12-09T22:06:34","modified_gmt":"2025-12-09T22:06:34","slug":"ricardo-gallardo-impulsa-la-ciencia-y-cultura-con-la-expo-tiburones","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2025\/12\/09\/ricardo-gallardo-impulsa-la-ciencia-y-cultura-con-la-expo-tiburones\/","title":{"rendered":"Ricardo Gallardo impulsa la ciencia y cultura con la Expo \u201cTiburones\u201d"},"content":{"rendered":"\n<p><strong>\u2022&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Invita a disfrutar sin l\u00edmites de una muestra interactiva que combina arte, ciencia y educaci\u00f3n ambiental para toda la familia.<\/strong><\/p>\n\n\n\n<p>El Gobernador de San Luis Potos\u00ed Ricardo Gallardo Cardona inaugur\u00f3 la exposici\u00f3n temporal \u201cTiburones\u201d en el Laberinto de las Ciencias y las Artes, un proyecto impulsado en colaboraci\u00f3n con la Fundaci\u00f3n Coppel, que eligi\u00f3 a San Luis Potos\u00ed como sede nacional.<\/p>\n\n\n\n<p>Durante la inauguraci\u00f3n, el Mandatario Estatal destac\u00f3 que esta exposici\u00f3n refleja el gran momento que vive el estado, especialmente en los \u00e1mbitos cultural, cient\u00edfico y educativo. \u201cEn este Gobierno San Luis Potos\u00ed se ha situado en el mapa internacional como nunca antes, tambi\u00e9n en el arte, la ciencia y la cultura\u201d, afirm\u00f3.<\/p>\n\n\n\n<p>La muestra, video-fotogr\u00e1fica e interactiva, ofrece a la juventud, a la ni\u00f1ez y a las familias potosinas la oportunidad de acercarse a la ciencia y al fascinante mundo de los tiburones. La exposici\u00f3n ha sido presentada en importantes recintos culturales, como el Museo de Historia Natural de la Ciudad de M\u00e9xico, y cuenta con el impulso del Museo Americano de Historia Natural de Nueva York.<\/p>\n\n\n\n<p>La exposici\u00f3n \u201cTiburones\u201d estar\u00e1 abierta al p\u00fablico en el Laberinto de las Ciencias y las Artes, ofreciendo una experiencia educativa y entretenida para que en estas vacaciones decembrinas familias potosinas y visitantes disfruten sin l\u00edmites.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u2022&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Invita a disfrutar sin l\u00edmites de una muestra interactiva que combina arte, ciencia y educaci\u00f3n ambiental para toda la familia. El Gobernador de San Luis Potos\u00ed Ricardo Gallardo Cardona inaugur\u00f3 la exposici\u00f3n temporal \u201cTiburones\u201d en el Laberinto de las Ciencias y las Artes, un proyecto impulsado en colaboraci\u00f3n con la Fundaci\u00f3n Coppel, que eligi\u00f3 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":26337,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[8],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/26317"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=26317"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/26317\/revisions"}],"predecessor-version":[{"id":26348,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/26317\/revisions\/26348"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/26337"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=26317"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=26317"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=26317"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}