{"id":26512,"date":"2025-12-13T11:33:00","date_gmt":"2025-12-13T11:33:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=26512"},"modified":"2025-12-13T21:14:44","modified_gmt":"2025-12-13T21:14:44","slug":"soledad-de-gs-cumple-y-avanza-en-la-estrategia-nacional-de-seguridad","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2025\/12\/13\/soledad-de-gs-cumple-y-avanza-en-la-estrategia-nacional-de-seguridad\/","title":{"rendered":"Soledad de GS cumple y avanza en la estrategia nacional de seguridad"},"content":{"rendered":"\n<ul>\n<li><strong>El Alcalde Juan Manuel Navarro Mu\u00f1iz destac\u00f3 que la preparaci\u00f3n y reconocimiento constante a la Guardia Civil Municipal, y el trabajo coordinado entre los tres niveles de gobierno, generan bondades de tranquilidad y protecci\u00f3n de la ciudadan\u00eda.<\/strong><\/li>\n<\/ul>\n\n\n\n<p>Juan Manuel Navarro Mu\u00f1iz, Alcalde de Soledad de Graciano S\u00e1nchez, destac\u00f3 el fortalecimiento del municipio como referente nacional en materia de seguridad p\u00fablica, al impulsar estrategias alineadas a la Estrategia Nacional de Seguridad que priorizan la capacitaci\u00f3n, certificaci\u00f3n y dignificaci\u00f3n de las y los elementos de la Guardia Civil Municipal, lo que ha permitido dar resultados a las familias y mantener cercan\u00eda, al contar con una de las corporaciones mejor preparadas y con mayor capacidad de respuesta ante il\u00edcitos.<\/p>\n\n\n\n<p>Lo anterior, lo subray\u00f3 al describir su participaci\u00f3n en la asamblea ordinaria de la Conferencia Nacional de Seguridad Municipal, dirigida por el secretario de Seguridad en el pa\u00eds, Omar Garc\u00eda Harfuch. Mencion\u00f3 que el Gobierno Municipal ha consolidado una pol\u00edtica de seguridad basada en sueldos dignos y justos, servicios m\u00e9dicos y procesos permanentes de evaluaci\u00f3n y control de confianza, entendiendo que la polic\u00eda municipal es el primer contacto de la ciudadan\u00eda ante una emergencia.<\/p>\n\n\n\n<p>\u201cEsta visi\u00f3n ha permitido que Soledad cumpla con est\u00e1ndares nacionales y sea ejemplo de c\u00f3mo la inversi\u00f3n en el capital humano impacta directamente en la tranquilidad de los hogares, de las y los j\u00f3venes, adultos mayores y sectores vulnerables\u201d.<\/p>\n\n\n\n<p>El Alcalde destac\u00f3 la relevancia de la coordinaci\u00f3n entre los tres niveles de gobierno, en especial con el Gobierno Estatal, como una de las claves para enfrentar los retos actuales en materia de seguridad, particularmente en la prevenci\u00f3n y la reducci\u00f3n en la percepci\u00f3n ciudadana en materia de seguridad. \u201cSomos el primer respondiente y el primer filtro de la ciudadan\u00eda; por eso es fundamental que nuestras y nuestros polic\u00edas est\u00e9n certificados, capacitados y con mejores condiciones laborales, adem\u00e1s de mantener una coordinaci\u00f3n s\u00f3lida con la Federaci\u00f3n, el Estado, la Guardia Nacional y el Ej\u00e9rcito, porque as\u00ed es como hemos dado resultados en Soledad\u201d, afirm\u00f3.<\/p>\n\n\n\n<p>Dijo que Soledad dio muestra del cumplimiento en las directrices nacionales, para reforzar la operaci\u00f3n y la labor de la Polic\u00eda Municipal, destacando que el Gobernador, Ricardo Gallardo Cardona, ha sido un aliado firme del municipio, en la creaci\u00f3n de planes operativos para afrontar y eliminar el fen\u00f3meno delictivo.<\/p>\n\n\n\n<p>La Administraci\u00f3n Municipal mantiene una ruta clara: trabajar de la mano con otras instancias, gestionar mayores recursos y sostener una estrategia que coloca a las familias soledenses en el centro de las decisiones, construyendo un municipio m\u00e1s seguro y con paz social.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Juan Manuel Navarro Mu\u00f1iz, Alcalde de Soledad de Graciano S\u00e1nchez, destac\u00f3 el fortalecimiento del municipio como referente nacional en materia de seguridad p\u00fablica, al impulsar estrategias alineadas a la Estrategia Nacional de Seguridad que priorizan la capacitaci\u00f3n, certificaci\u00f3n y dignificaci\u00f3n de las y los elementos de la Guardia Civil Municipal, lo que ha permitido dar [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":26513,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[10],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/26512"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=26512"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/26512\/revisions"}],"predecessor-version":[{"id":26514,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/26512\/revisions\/26514"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/26513"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=26512"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=26512"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=26512"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}