{"id":26636,"date":"2025-12-16T16:55:00","date_gmt":"2025-12-16T16:55:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=26636"},"modified":"2025-12-17T00:03:44","modified_gmt":"2025-12-17T00:03:44","slug":"san-luis-capital-avanza-en-hermanamientos-con-ciudades-nacionales-e-internacionales","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2025\/12\/16\/san-luis-capital-avanza-en-hermanamientos-con-ciudades-nacionales-e-internacionales\/","title":{"rendered":"San Luis Capital avanza en hermanamientos con ciudades nacionales e internacionales"},"content":{"rendered":"\n<ul>\n<li><strong>La Comisi\u00f3n de Asuntos Internacionales del ayuntamiento aprob\u00f3 en sesi\u00f3n la propuesta para oficializar v\u00ednculos con Colima, Colima; San Nicol\u00e1s de los Garza, NL; y Sevilla, Espa\u00f1a.<\/strong><\/li>\n<\/ul>\n\n\n\n<p>En sesi\u00f3n ordinaria de la comisi\u00f3n de Asuntos Internacionales del Ayuntamiento de San Luis Capital, regidoras y regidores analizaron favorablemente la solicitud del alcalde Enrique Galindo Ceballos para oficializar el hermanamiento con los municipios de Colima, Colima; San Nicol\u00e1s de los Garza, Nuevo Le\u00f3n; y Sevilla, Espa\u00f1a. Este acuerdo ser\u00e1 presentado pr\u00f3ximamente ante el Pleno del Cabildo para su ratificaci\u00f3n.<\/p>\n\n\n\n<p>El Regidor Francisco Javier Pedraza Blanco, Presidente de la Comisi\u00f3n, destac\u00f3 que estas alianzas fortalecer\u00e1n \u00e1reas como la cultura, el deporte, el turismo y la academia, beneficiando a los actores sociales involucrados mediante intercambios que enriquecer\u00e1n a la comunidad potosina.<\/p>\n\n\n\n<p>Mencion\u00f3 el edil que, hasta ahora, durante los dos periodos de la actual administraci\u00f3n, San Luis Potos\u00ed ha concretado hermanamientos con cuatro ciudades, incluyendo Tucson, Arizona. Pedraza Blanco adelant\u00f3 que continuar\u00e1n explorando nuevas oportunidades de cooperaci\u00f3n, mencionando contactos con Alemania y otros municipios mexicanos para ampliar la red internacional.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En sesi\u00f3n ordinaria de la comisi\u00f3n de Asuntos Internacionales del Ayuntamiento de San Luis Capital, regidoras y regidores analizaron favorablemente la solicitud del alcalde Enrique Galindo Ceballos para oficializar el hermanamiento con los municipios de Colima, Colima; San Nicol\u00e1s de los Garza, Nuevo Le\u00f3n; y Sevilla, Espa\u00f1a. Este acuerdo ser\u00e1 presentado pr\u00f3ximamente ante el Pleno [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":26637,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[4],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/26636"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=26636"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/26636\/revisions"}],"predecessor-version":[{"id":26638,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/26636\/revisions\/26638"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/26637"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=26636"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=26636"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=26636"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}