{"id":26674,"date":"2025-12-17T12:15:00","date_gmt":"2025-12-17T12:15:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=26674"},"modified":"2025-12-17T20:49:31","modified_gmt":"2025-12-17T20:49:31","slug":"espectaculares-conciertos-llenan-de-musica-templos-capitalinos","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2025\/12\/17\/espectaculares-conciertos-llenan-de-musica-templos-capitalinos\/","title":{"rendered":"Espectaculares conciertos llenan de m\u00fasica templos capitalinos."},"content":{"rendered":"\n<ul>\n<li><strong>La Secretar\u00eda de Cultura presenta a la Orquesta Sinf\u00f3nica con motivo de la Navidad verde.&nbsp; Los dias 18 y 19 de diciembre se presentar\u00e1 en&nbsp; la Catedral potosina y Tlaxcala.<\/strong><\/li>\n<\/ul>\n\n\n\n<p>En el marco de la Navidad Verde, programa que impulsa el Gobierno del Estado, encabezado por Ricardo Gallardo Cardona; la Secretar\u00eda de Cultura desarrolla una serie de conciertos navide\u00f1os con el prop\u00f3sito de llevar la oferta cultural a distintos espacios de la ciudad y acercar la m\u00fasica sinf\u00f3nica a p\u00fablicos diversos durante la temporada decembrina.<\/p>\n\n\n\n<p>Como parte de estas actividades, la Orquesta Sinf\u00f3nica, se present\u00f3 en el Santuario de la Bas\u00edlica de Guadalupe con un programa especialmente dise\u00f1ado para celebrar la Navidad, bajo la direcci\u00f3n del maestro Enrique Barrios y con la participaci\u00f3n del Coro Polif\u00f3nico del SEER, logrando una respuesta entusiasta por parte de las y los asistentes.<\/p>\n\n\n\n<p>El secretario de Cultura, Mario Garc\u00eda Valdez, dijo que estas presentaciones reafirman el compromiso del Gobierno del Estado de promover el acceso a la cultura y fortalecer las tradiciones, al llevar espect\u00e1culos de alta calidad a recintos hist\u00f3ricos y religiosos que se convierten en puntos de encuentro para la convivencia familiar y comunitaria.<\/p>\n\n\n\n<p>La Secretar\u00eda de Cultura invita a la ciudadan\u00eda a disfrutar de los pr\u00f3ximos conciertos gratuitos de la Orquesta Sinf\u00f3nica de San Luis Potos\u00ed, que se realizar\u00e1n los d\u00edas 18 y 19 de diciembre, a las 20:00 horas, en los templos de la Catedral Metropolitana y Tlaxcala como parte de las celebraciones de la Navidad Verde 2025.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el marco de la Navidad Verde, programa que impulsa el Gobierno del Estado, encabezado por Ricardo Gallardo Cardona; la Secretar\u00eda de Cultura desarrolla una serie de conciertos navide\u00f1os con el prop\u00f3sito de llevar la oferta cultural a distintos espacios de la ciudad y acercar la m\u00fasica sinf\u00f3nica a p\u00fablicos diversos durante la temporada decembrina. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":26675,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[6],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/26674"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=26674"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/26674\/revisions"}],"predecessor-version":[{"id":26676,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/26674\/revisions\/26676"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/26675"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=26674"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=26674"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=26674"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}