{"id":26697,"date":"2025-12-17T17:40:00","date_gmt":"2025-12-17T17:40:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=26697"},"modified":"2025-12-18T01:33:42","modified_gmt":"2025-12-18T01:33:42","slug":"ceepac-presento-informes-frente-al-cierre-de-actividades-del-2025","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2025\/12\/17\/ceepac-presento-informes-frente-al-cierre-de-actividades-del-2025\/","title":{"rendered":"CEEPAC present\u00f3 informes frente al cierre de actividades del 2025."},"content":{"rendered":"\n<p>El Consejo General del Consejo Estatal Electoral y de Participaci\u00f3n Ciudadana (CEEPAC) en sesi\u00f3n ordinaria con partidos pol\u00edticos, present\u00f3 diversos informes y asuntos relevantes para el desarrollo de las funciones institucionales del organismo.<\/p>\n\n\n\n<p>Durante la sesi\u00f3n se present\u00f3 el informe relativo a la clausura de los trabajos y cierre de la Comisi\u00f3n Temporal de Inclusi\u00f3n con Representaciones Ind\u00edgenas, en cumplimiento a la sentencia emitida por el Tribunal Electoral del Estado de San Luis Potos\u00ed, dentro del expediente TESLP-JDC-11\/2023 y acumulados.<\/p>\n\n\n\n<p>De igual forma, se rindi\u00f3 el informe sobre la interposici\u00f3n y seguimiento de las quejas y denuncias tramitadas ante el CEEPAC, correspondiente al per\u00edodo comprendido del 14 de noviembre al 11 de diciembre de 2025, as\u00ed como, el informe de los medios de impugnaci\u00f3n interpuestos ante este organismo electoral y de las resoluciones emitidas por el Tribunal Electoral del Estado, correspondientes al per\u00edodo del 15 de noviembre al 11 de diciembre de 2025.<\/p>\n\n\n\n<p>En otro punto del Orden del D\u00eda, se present\u00f3 el informe sobre el presupuesto de egresos del Ejercicio Fiscal 2025, adem\u00e1s del informe de correspondencia recibida, referente al per\u00edodo del 08 de noviembre al 05 de diciembre de 2025.<\/p>\n\n\n\n<p>Finalmente, se present\u00f3 el informe anual de la coordinaci\u00f3n de G\u00e9nero e Inclusi\u00f3n en la que se se\u00f1al\u00f3 que:&nbsp;<\/p>\n\n\n\n<p>Se asisti\u00f3 a doce sesiones ordinarias de la Comisi\u00f3n Permanente de G\u00e9nero e Inclusi\u00f3n, en calidad de Secretar\u00eda T\u00e9cnica; Se llevaron a cabo acciones conmemorativas relacionadas con la agenda de derechos humanos de grupos prioritarios; Se coordinaron actividades de trabajo con las redes de mujeres electas y juzgadoras;&nbsp; Se coordin\u00f3 el Diagn\u00f3stico de violencia pol\u00edtica contra las mujeres del proceso electoral 2024; Se coordin\u00f3 el plan de trabajo del Observatorio de Participaci\u00f3n Pol\u00edtica de las Mujeres en el Estado; se brindaron diversas capacitaciones permanentes al personal de CEEPAC y al funcionariado de los organismos electorales desconcentrados; adem\u00e1s se brind\u00f3 atenci\u00f3n de primer contacto en casos de violencia pol\u00edtica en raz\u00f3n de g\u00e9nero (VPRG).<\/p>\n\n\n\n<p>Con estas acciones, el CEEPAC refrenda su compromiso con la legalidad, la transparencia y el adecuado cumplimiento de sus atribuciones constitucionales y legales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Consejo General del Consejo Estatal Electoral y de Participaci\u00f3n Ciudadana (CEEPAC) en sesi\u00f3n ordinaria con partidos pol\u00edticos, present\u00f3 diversos informes y asuntos relevantes para el desarrollo de las funciones institucionales del organismo. Durante la sesi\u00f3n se present\u00f3 el informe relativo a la clausura de los trabajos y cierre de la Comisi\u00f3n Temporal de Inclusi\u00f3n [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":26698,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[13],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/26697"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=26697"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/26697\/revisions"}],"predecessor-version":[{"id":26699,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/26697\/revisions\/26699"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/26698"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=26697"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=26697"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=26697"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}