{"id":2825,"date":"2024-05-01T12:30:00","date_gmt":"2024-05-01T12:30:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=2825"},"modified":"2024-05-01T21:20:28","modified_gmt":"2024-05-01T21:20:28","slug":"con-multiples-y-divertidas-actividades-soledad-de-gs-celebro-a-las-y-los-ninos-de-diversas-colonias","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2024\/05\/01\/con-multiples-y-divertidas-actividades-soledad-de-gs-celebro-a-las-y-los-ninos-de-diversas-colonias\/","title":{"rendered":"Con m\u00faltiples y divertidas actividades, Soledad de GS celebr\u00f3 a las y los ni\u00f1os de diversas colonias"},"content":{"rendered":"\n<p><strong>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Distintas dependencias municipales planearon festejos para las y los peque\u00f1os soledenses, que incluyeron regalos y dulces adem\u00e1s de momentos de diversi\u00f3n.<\/strong><\/p>\n\n\n\n<p>Con m\u00faltiples actividades coloridas, entusiastas y l\u00fadicas, se celebr\u00f3 de forma especial este 30 de abril con motivo del D\u00eda del Ni\u00f1o y de la Ni\u00f1a, en la que destacaron la entrega de regalos, juegos mec\u00e1nicos, inflables, postres, dulces y regalos para todas y todos los peque\u00f1os.<\/p>\n\n\n\n<p>La Coordinaci\u00f3n de Promoci\u00f3n Ciudadana organiz\u00f3 un festejo en el Auditorio de la colonia San Felipe, donde se congregaron m\u00e1s de 300 ni\u00f1os y ni\u00f1as de diversas colonias aleda\u00f1as, en una jornada que comenz\u00f3 a las 5:30 de la tarde y se extendi\u00f3 hasta las 10 de la noche, con m\u00fasica y alegr\u00eda para todos los asistentes.<\/p>\n\n\n\n<p>Los ni\u00f1os disfrutaron de snacks en los que se incluyeron molletes, nachos, gelatinas, panquecitos, aguas frescas, bolis, dulces y juguetes, los cuales fueron distribuidos entre todos los presentes, adem\u00e1s durante el evento, se incluyeron actividades de entretenimiento como inflables, el popular toro mec\u00e1nico y una clase de Zumba adaptada para las y los festejados.<\/p>\n\n\n\n<p>Por su parte, la Direcci\u00f3n de Deporte Municipal encabez\u00f3 una Rodada Nocturna, que en esta ocasi\u00f3n fue dedicada a las y los ni\u00f1os soledenses, donde acompa\u00f1ados por sus familias, recibieron juguetes y dulces como parte de las festividades, llevando su bicicleta adornada y con m\u00fasica infantil que las y los acompa\u00f1\u00f3 en todo el recorrido.<\/p>\n\n\n\n<p>Asimismo, la Coordinaci\u00f3n de Bibliotecas Municipales tambi\u00e9n se sum\u00f3 a esta celebraci\u00f3n, haciendo entrega de pelotas y m\u00e1s dulces a las y los menores en las calles principales de Cabecera municipal, promoviendo as\u00ed el fomento de la lectura y la convivencia positiva entre familias, madres, padres de familia y sus hijas e hijos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Distintas dependencias municipales planearon festejos para las y los peque\u00f1os soledenses, que incluyeron regalos y dulces adem\u00e1s de momentos de diversi\u00f3n. Con m\u00faltiples actividades coloridas, entusiastas y l\u00fadicas, se celebr\u00f3 de forma especial este 30 de abril con motivo del D\u00eda del Ni\u00f1o y de la Ni\u00f1a, en la que destacaron la entrega de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2826,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[10],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/2825"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=2825"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/2825\/revisions"}],"predecessor-version":[{"id":2827,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/2825\/revisions\/2827"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/2826"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=2825"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=2825"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=2825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}