{"id":28610,"date":"2026-02-01T17:10:00","date_gmt":"2026-02-01T17:10:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=28610"},"modified":"2026-02-02T05:39:08","modified_gmt":"2026-02-02T05:39:08","slug":"servicios-estatales-garantizados-durante-el-primer-puente-del-ano","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2026\/02\/01\/servicios-estatales-garantizados-durante-el-primer-puente-del-ano\/","title":{"rendered":"Servicios estatales garantizados durante el primer puente del a\u00f1o"},"content":{"rendered":"\n<ul>\n<li><strong>Dependencias operativas y \u00e1reas clave mantendr\u00e1n atenci\u00f3n continua para no interrumpir los servicios.<\/strong><\/li>\n<\/ul>\n\n\n\n<p>Con motivo del d\u00eda de descanso obligatorio del lunes 2 de febrero, la Oficial\u00eda Mayor (OM) inform\u00f3 que se implementar\u00e1n esquemas de guardias en las dependencias estatales, a fin de asegurar la continuidad de los servicios p\u00fablicos y la atenci\u00f3n a la ciudadan\u00eda durante este primer puente del a\u00f1o.<\/p>\n\n\n\n<p>Las \u00e1reas operativas como la Secretar\u00eda de Seguridad y Protecci\u00f3n Ciudadana (SSPCE), la Coordinaci\u00f3n Estatal de Protecci\u00f3n Civil (CEPC), los Servicios de Salud y la Secretar\u00eda de las Mujeres e Igualdad Sustantiva (Semujeres) mantendr\u00e1n su funcionamiento habitual, conforme a sus protocolos, para garantizar respuesta inmediata ante emergencias. Esta disposici\u00f3n se enmarca en la din\u00e1mica de trabajo permanente que ha marcado el Gobernador Ricardo Gallardo Cardona para mantener un Gobierno cercano y en operaci\u00f3n constante.<\/p>\n\n\n\n<p>En tanto, las dependencias administrativas asegurar\u00e1n la prestaci\u00f3n de servicios indispensables sin afectar a las y los usuarios. Con esta organizaci\u00f3n, el Gobierno del Estado reafirma una forma de gobernar sin l\u00edmites en la atenci\u00f3n a la ciudadan\u00eda, como parte del cambio que se vive y se siente en San Luis Potos\u00ed.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con motivo del d\u00eda de descanso obligatorio del lunes 2 de febrero, la Oficial\u00eda Mayor (OM) inform\u00f3 que se implementar\u00e1n esquemas de guardias en las dependencias estatales, a fin de asegurar la continuidad de los servicios p\u00fablicos y la atenci\u00f3n a la ciudadan\u00eda durante este primer puente del a\u00f1o. Las \u00e1reas operativas como la Secretar\u00eda [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":28611,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[3],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/28610"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=28610"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/28610\/revisions"}],"predecessor-version":[{"id":28612,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/28610\/revisions\/28612"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/28611"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=28610"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=28610"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=28610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}