{"id":28936,"date":"2026-02-09T12:40:00","date_gmt":"2026-02-09T12:40:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=28936"},"modified":"2026-02-09T19:02:49","modified_gmt":"2026-02-09T19:02:49","slug":"villa-de-pozos-invita-a-emprendedores-y-artesanos-a-formar-parte-del-pabellon-del-dia-del-amor-y-la-amistad","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2026\/02\/09\/villa-de-pozos-invita-a-emprendedores-y-artesanos-a-formar-parte-del-pabellon-del-dia-del-amor-y-la-amistad\/","title":{"rendered":"Villa de Pozos invita a emprendedores y artesanos a formar parte del pabell\u00f3n del D\u00eda del Amor y la Amistad"},"content":{"rendered":"\n<ul>\n<li><strong>Se convoca a emprendedores y artesanos del municipio a participar en el Pabell\u00f3n Emprendedor del D\u00eda del Amor y la Amistad este 13 y 14 de febrero.<\/strong><\/li>\n<\/ul>\n\n\n\n<p>El Gobierno Municipal de Villa de Pozos, a trav\u00e9s de la direcci\u00f3n de Desarrollo Econ\u00f3mico, convocan a emprendedores y artesanos a participar en el Pabell\u00f3n Emprendedor del D\u00eda del Amor y la Amistad, para impulsar la econom\u00eda local y brindar espacios de promoci\u00f3n.<\/p>\n\n\n\n<p>Se llevar\u00e1 a cabo los d\u00edas 13 y 14 de febrero en la Plaza Principal de Villa de Pozos en un horario de 10 de la ma\u00f1ana a 8 de la noche, las y los participantes ofrecer\u00e1n una gran variedad de productos alusivos a esta fecha especial.<\/p>\n\n\n\n<p>El titular de la direcci\u00f3n de Desarrollo Econ\u00f3mico, Juan Alejandro M\u00e9ndez Zavala, mencion\u00f3 que la convocatoria va dirigida a emprendedores y artesanos poce\u00f1os interesados en dar conocer sus productos, brind\u00e1ndoles el espacio para exhibir y comercializar sus creaciones en un ambiente de convivencia.<\/p>\n\n\n\n<p>Las y los interesados deber\u00e1n acudir a las oficinas de Desarrollo Econ\u00f3mico ubicadas dentro del Palacio Municipal, para realizar su registro este lunes 9 y martes 10 de febrero en horario de oficina y podr\u00e1n comunicarse a trav\u00e9s del n\u00famero telef\u00f3nico 444 703 7189 para m\u00e1s informes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Gobierno Municipal de Villa de Pozos, a trav\u00e9s de la direcci\u00f3n de Desarrollo Econ\u00f3mico, convocan a emprendedores y artesanos a participar en el Pabell\u00f3n Emprendedor del D\u00eda del Amor y la Amistad, para impulsar la econom\u00eda local y brindar espacios de promoci\u00f3n. Se llevar\u00e1 a cabo los d\u00edas 13 y 14 de febrero en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":28937,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/28936"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=28936"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/28936\/revisions"}],"predecessor-version":[{"id":28938,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/28936\/revisions\/28938"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/28937"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=28936"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=28936"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=28936"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}