{"id":30379,"date":"2026-03-06T16:20:00","date_gmt":"2026-03-06T16:20:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=30379"},"modified":"2026-03-06T23:41:55","modified_gmt":"2026-03-06T23:41:55","slug":"empoderamiento-femenino-con-espiritu-critico-y-educacion-expone-silvia-olmedo-en-su-conferencia-a-las-mujeres-potosinas","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2026\/03\/06\/empoderamiento-femenino-con-espiritu-critico-y-educacion-expone-silvia-olmedo-en-su-conferencia-a-las-mujeres-potosinas\/","title":{"rendered":"Empoderamiento femenino con esp\u00edritu cr\u00edtico y educaci\u00f3n, expone Silvia Olmedo en su conferencia a las mujeres potosinas"},"content":{"rendered":"\n<ul>\n<li><strong>La conferencista Silvia Olmedo comparti\u00f3 que para empoderar es indispensable superar las ideas limitantes, adem\u00e1s de que las mujeres crean en s\u00ed mismas.<\/strong><\/li>\n<\/ul>\n\n\n\n<p>En el arranque de las conferencias magistrales por el 8M \u00abUnidas somos Poderosas\u00bb, acompa\u00f1ada por el Alcalde, Enrique Galindo Ceballos; la Presidenta del DIF Capitalino, Estela Arriaga M\u00e1rquez confirm\u00f3 la relevancia del empoderamiento de las mujeres, cuya responsabilidad del Gobierno de la Capital es la base para lograrlo, adem\u00e1s de impulsar su desarrollo personal y comunitario.<\/p>\n\n\n\n<p>Arriaga M\u00e1rquez insisti\u00f3 tambi\u00e9n en la importancia de fomentar la independencia econ\u00f3mica, la salud y acciones para que gocen de una vida libre de violencia, mediante la coinversi\u00f3n social. Record\u00f3 que \u00aben San Luis Capital desde 2022, el Alcalde Enrique Galindo asumi\u00f3 el compromiso de fomentar la igualdad a trav\u00e9s de pol\u00edticas p\u00fablicas, programas y estrategias transversales y con perspectiva de g\u00e9nero, con trabajo diario y permanente. Por ello se impulsa el emprendimiento entre mujeres, se detectan y erradican las violencias, para lo que, es necesario escuchar y hablar siempre\u00bb.<\/p>\n\n\n\n<p>El Presidente Municipal Enrique Galindo subray\u00f3 el gran mensaje de empoderamiento de la conferencista, Silvia Olmedo, a quien le agradeci\u00f3 los conocimientos compartidos, no solo para las potosinas, sino para la poblaci\u00f3n en general.<\/p>\n\n\n\n<p><strong>CLAVES DE UN VERDADERO EMPODERAMIENTO<\/strong><\/p>\n\n\n\n<p>En su ponencia \u00abClaves de un verdadero empoderamiento\u00bb, la conferencista internacional Silvia Olmedo, emocionada comparti\u00f3 la relevancia de tomar decisiones, pero siempre estando debidamente informadas, a la par de tener un esp\u00edritu cr\u00edtico.&nbsp; Resalt\u00f3 que San Luis Capital es un Municipio donde hay igualdad y se reconoce a las mujeres.<\/p>\n\n\n\n<p>Puntualiz\u00f3 que el empoderamiento se da en varias esferas, desde lo pol\u00edtico hasta la participaci\u00f3n de las propias mujeres, en cuyo proceso es fundamental tomar en cuenta el impacto de la autoestima y los v\u00ednculos afectivos, el asertividad, el entorno social, con el prop\u00f3sito de ayudar e impulsar a las mujeres.<\/p>\n\n\n\n<p>La especialista espa\u00f1ola resalt\u00f3 que al ser San Luis Capital Ciudad del Aprendizaje se deben superar las ideas limitantes para sanar, a trav\u00e9s de la educaci\u00f3n para cambiar el mundo \u00aby la idea de la mujer abnegada o sacrificada para terminar con las violencias contra ellas. Asimismo, insisti\u00f3 en la importancia de contar con redes de apoyo especializadas. De manera amena, atenta y clara, exhort\u00f3 a las potosinas a cambiar por s\u00ed mismas, a poner l\u00edmites y resignificar su vida para alcanzar sus objetivos\u201d.<\/p>\n\n\n\n<p>Ante un auditorio lleno, la Presidenta del DIF Capitalino, Estela Arriaga; el Alcalde Enrique Galindo y la Regidora Presidenta de la Comisi\u00f3n de Atenci\u00f3n a las Mujeres, Luz Magdalena Cisneros, entregaron un reconocimiento a la doctora, sex\u00f3loga y psic\u00f3loga Silvia Olmedo por compartir no s\u00f3lo su conocimiento sino experiencias personales para empoderar a las mujeres de San Luis Capital.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el arranque de las conferencias magistrales por el 8M \u00abUnidas somos Poderosas\u00bb, acompa\u00f1ada por el Alcalde, Enrique Galindo Ceballos; la Presidenta del DIF Capitalino, Estela Arriaga M\u00e1rquez confirm\u00f3 la relevancia del empoderamiento de las mujeres, cuya responsabilidad del Gobierno de la Capital es la base para lograrlo, adem\u00e1s de impulsar su desarrollo personal y [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":30380,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[4],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/30379"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=30379"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/30379\/revisions"}],"predecessor-version":[{"id":30381,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/30379\/revisions\/30381"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/30380"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=30379"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=30379"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=30379"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}