{"id":30454,"date":"2026-03-07T14:50:00","date_gmt":"2026-03-07T14:50:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=30454"},"modified":"2026-03-08T02:51:28","modified_gmt":"2026-03-08T02:51:28","slug":"sin-licencia-ni-dictamenes-direccion-de-comercio-municipal-clausura-tres-establecimientos-de-grandes-cadenas-comerciales","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2026\/03\/07\/sin-licencia-ni-dictamenes-direccion-de-comercio-municipal-clausura-tres-establecimientos-de-grandes-cadenas-comerciales\/","title":{"rendered":"Sin licencia ni dict\u00e1menes: Direcci\u00f3n de Comercio Municipal, clausura tres establecimientos de grandes cadenas comerciales"},"content":{"rendered":"\n<ul>\n<li><strong>Las clausuras se aplicaron a establecimientos de Soriana, Sodimac e IHOP, que no contaban con licencia de funcionamiento vigente ni con los dict\u00e1menes municipales necesarios para operar conforme a la ley en San Luis Potos\u00ed.<\/strong><\/li>\n<\/ul>\n\n\n\n<p>Como parte del operativo permanente de supervisi\u00f3n que se realiza a trav\u00e9s de recorridos en distintos puntos de la ciudad, el Gobierno Municipal de San Luis Potos\u00ed, por medio de la Direcci\u00f3n de Comercio, llev\u00f3 a cabo durante la semana la clausura de tres establecimientos que son parte de cadenas comerciales y franquicias.<\/p>\n\n\n\n<p>Las acciones de verificaci\u00f3n derivaron en la clausura de establecimientos correspondientes a Soriana, Sodimac y la franquicia restaurantera IHOP, luego de que durante las inspecciones se detectara que no contaban con licencia de funcionamiento vigente, adem\u00e1s de carecer de los dict\u00e1menes municipales necesarios, los cuales son requisitos indispensables para poder operar conforme a la normatividad municipal.<\/p>\n\n\n\n<p>La Direcci\u00f3n de Comercio inform\u00f3 que las acciones de supervisi\u00f3n se mantienen de manera permanente en distintos puntos de la ciudad, como parte de una estrategia para verificar que los establecimientos cumplan con la normatividad municipal vigente.<\/p>\n\n\n\n<p>Estas revisiones buscan ordenar la actividad comercial, fortalecer la legalidad en el funcionamiento de los negocios y asegurar que todos los establecimientos operen con seguridad, generando as\u00ed mayor confianza para la poblaci\u00f3n.<\/p>\n\n\n\n<p>La Direcci\u00f3n de Comercio hace un llamado a todos los establecimientos comerciales de la ciudad para que regularicen su situaci\u00f3n administrativa, tramiten su licencia de funcionamiento y cuenten con los dict\u00e1menes correspondientes, a fin de evitar sanciones y asegurar que sus actividades se desarrollen dentro del marco legal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Como parte del operativo permanente de supervisi\u00f3n que se realiza a trav\u00e9s de recorridos en distintos puntos de la ciudad, el Gobierno Municipal de San Luis Potos\u00ed, por medio de la Direcci\u00f3n de Comercio, llev\u00f3 a cabo durante la semana la clausura de tres establecimientos que son parte de cadenas comerciales y franquicias. Las acciones [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":30455,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[4],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/30454"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=30454"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/30454\/revisions"}],"predecessor-version":[{"id":30456,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/30454\/revisions\/30456"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/30455"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=30454"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=30454"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=30454"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}