{"id":31145,"date":"2026-03-22T11:17:00","date_gmt":"2026-03-22T11:17:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=31145"},"modified":"2026-03-22T22:28:39","modified_gmt":"2026-03-22T22:28:39","slug":"copa-potosi-reune-a-grandes-estrellas-del-futbol-femenil","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2026\/03\/22\/copa-potosi-reune-a-grandes-estrellas-del-futbol-femenil\/","title":{"rendered":"Copa Potos\u00ed re\u00fane a grandes estrellas del f\u00fatbol femenil"},"content":{"rendered":"\n<ul>\n<li><strong>La Copa Potos\u00ed 2026 re\u00fane a destacadas ex jugadoras de la Liga MX Femenil, elevando el nivel competitivo y consolidando el impulso al deporte en el Estado.<\/strong><\/li>\n<\/ul>\n\n\n\n<p>Como parte del apoyo sin l\u00edmites del Gobernador Ricardo Gallardo Cardona al deporte, la Copa Potos\u00ed 2026 marca un precedente con la participaci\u00f3n de ex jugadoras de la Liga MX Femenil, quienes han formado parte de equipos como Chivas, Am\u00e9rica, Le\u00f3n, Pachuca, Tijuana, Ju\u00e1rez y Mazatl\u00e1n, garantizando un alto nivel de competencia.<\/p>\n\n\n\n<p>Entre las futbolistas destacadas se encuentran Adriana Calzadillas, de Xolas de Tijuana; Karen Llamas, con trayectoria en Am\u00e9rica, Toluca y la Selecci\u00f3n Mexicana; as\u00ed como Sandra Camacho, Karen Hern\u00e1ndez y Jessica Cu\u00e9llar, con experiencia en Le\u00f3n, adem\u00e1s de Hilary Garc\u00eda, ex jugadora de Chivas. Tambi\u00e9n participar\u00e1n Daniela Auza, de Bravas de Ju\u00e1rez; Perla Navarrete, con paso por Le\u00f3n, Tigres, Santos, FC Ju\u00e1rez y Necaxa; Dayana Navarrete, de Le\u00f3n; Paulina G\u00f3mez, ex jugadora de Le\u00f3n y Pachuca; as\u00ed como Kenia Camacho, de Mazatl\u00e1n, y Diana P\u00e9rez, de Necaxa Femenil.<\/p>\n\n\n\n<p>Para esta edici\u00f3n, adem\u00e1s participa el equipo femenil del Colegio de Bachilleres del Estado (Cobach) y los equipos femeniles se han reforzado significativamente con el objetivo de ofrecer su mejor desempe\u00f1o del 30 de marzo al 4 de abril, en el marco de Semana Santa, consolidando el cambio que se vive y se siente en el deporte, haciendo una aut\u00e9ntica fiesta del f\u00fatbol. La Copa Potos\u00ed reafirma su crecimiento como uno de los torneos amateur m\u00e1s importantes del pa\u00eds, impulsando sin l\u00edmites el talento femenil y generando espacios de competencia de alto nivel.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Como parte del apoyo sin l\u00edmites del Gobernador Ricardo Gallardo Cardona al deporte, la Copa Potos\u00ed 2026 marca un precedente con la participaci\u00f3n de ex jugadoras de la Liga MX Femenil, quienes han formado parte de equipos como Chivas, Am\u00e9rica, Le\u00f3n, Pachuca, Tijuana, Ju\u00e1rez y Mazatl\u00e1n, garantizando un alto nivel de competencia. Entre las futbolistas [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":31146,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[5],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/31145"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=31145"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/31145\/revisions"}],"predecessor-version":[{"id":31147,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/31145\/revisions\/31147"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/31146"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=31145"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=31145"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=31145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}