{"id":31261,"date":"2026-03-24T16:38:00","date_gmt":"2026-03-24T16:38:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=31261"},"modified":"2026-03-24T23:07:36","modified_gmt":"2026-03-24T23:07:36","slug":"estado-fortalece-acciones-contra-el-gusano-barrenador","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2026\/03\/24\/estado-fortalece-acciones-contra-el-gusano-barrenador\/","title":{"rendered":"Estado fortalece acciones contra el gusano barrenador"},"content":{"rendered":"\n<ul>\n<li><strong>Convoca a alcald\u00edas y asociaciones ganaderas a sumarse al combate, con acciones coordinadas para proteger la salud animal y a productores.<\/strong><\/li>\n<\/ul>\n\n\n\n<p>Como parte de la prioridad que el Gobernador Ricardo Gallardo Cardona ha dado a atender al sector pecuario, la Secretar\u00eda de Desarrollo Agropecuario y Recursos Hidr\u00e1ulicos (Sedarh) fortalece el combate a la plaga del gusano barrenador del ganado mediante la ampliaci\u00f3n de labores de control sanitario. La estrategia contempla la participaci\u00f3n de ayuntamientos y asociaciones ganaderas para atender animales heridos, aplicar tratamientos y contener la presencia de la mosca Cochliomyia hominivorax en las zonas con casos detectados.<\/p>\n\n\n\n<p>En una reuni\u00f3n con alcaldes de la regi\u00f3n Media y la Secretar\u00eda de Agricultura y Desarrollo Rural (Sader), acord\u00f3 coordinar esfuerzos para realizar curaciones, muestreos y fumigaci\u00f3n en puntos cr\u00edticos, como parte de un trabajo sin l\u00edmites para proteger la actividad ganadera y reducir los riesgos sanitarios, con el respaldo del Sistema Nacional de Sanidad, Inocuidad y Calidad Agroalimentaria (Senasica) y la Comisi\u00f3n M\u00e9xico-Estados Unidos para la Prevenci\u00f3n de la Fiebre Aftosa y Enfermedades Tropicales (CPA).<\/p>\n\n\n\n<p>El pr\u00f3ximo 26 de marzo se replicar\u00e1 este encuentro con la Huasteca, donde se buscar\u00e1 reforzar la participaci\u00f3n local y la atenci\u00f3n oportuna de casos, adem\u00e1s de implementar campa\u00f1as como la liberaci\u00f3n de mosca est\u00e9ril y t\u00e9cnicas de control. Acompa\u00f1ando el cambio que se vive y se siente, estas acciones permiten fortalecer la atenci\u00f3n al campo y mejorar las condiciones para las y los productores potosinos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Como parte de la prioridad que el Gobernador Ricardo Gallardo Cardona ha dado a atender al sector pecuario, la Secretar\u00eda de Desarrollo Agropecuario y Recursos Hidr\u00e1ulicos (Sedarh) fortalece el combate a la plaga del gusano barrenador del ganado mediante la ampliaci\u00f3n de labores de control sanitario. La estrategia contempla la participaci\u00f3n de ayuntamientos y asociaciones [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":31262,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[3],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/31261"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=31261"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/31261\/revisions"}],"predecessor-version":[{"id":31263,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/31261\/revisions\/31263"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/31262"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=31261"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=31261"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=31261"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}