{"id":322,"date":"2024-03-06T16:15:00","date_gmt":"2024-03-06T16:15:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=322"},"modified":"2024-03-07T05:18:11","modified_gmt":"2024-03-07T05:18:11","slug":"coaliciones-definen-el-siglado-de-candidaturas-a-diputaciones-locales","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2024\/03\/06\/coaliciones-definen-el-siglado-de-candidaturas-a-diputaciones-locales\/","title":{"rendered":"Coaliciones definen el siglado de candidaturas a diputaciones locales"},"content":{"rendered":"\n<p>El Consejo General del Consejo Estatal Electoral y de Participaci\u00f3n Ciudadana (CEEPAC) aprob\u00f3 las modificaciones de los convenios de las coaliciones:\u00a0 \u201cSigamos Haciendo Historia en San Luis Potos\u00ed\u201d, integrada por los partidos pol\u00edticos Morena, del Trabajo (PT ) y Verde Ecologista de M\u00e9xico (PVEM), y la Coalici\u00f3n Fuerza y Coraz\u00f3n por San Luis integrada por los partidos Acci\u00f3n Nacional (PAN), Revolucionario Institucional (PRI) y de la Revoluci\u00f3n Democr\u00e1tica (PRD), para el proceso electoral local 2024.<\/p>\n\n\n\n<p>Las Coaliciones son alianzas temporales y transitorias que sostienen dos o m\u00e1s partidos pol\u00edticos, con el prop\u00f3sito de alcanzar fines comunes de car\u00e1cter electoral y postular candidaturas a puestos de elecci\u00f3n popular, esto implica la coincidencia de sus integrantes y una actuaci\u00f3n conjunta en el registro de las candidaturas para las elecciones en las que participen, en San Luis Potos\u00ed est\u00e1n contendiendo en el proceso electoral las dos coaliciones antes se\u00f1aladas.<\/p>\n\n\n\n<p>La Coalici\u00f3n Sigamos Haciendo Historia en San Luis Potos\u00ed, modific\u00f3 el siglado de los cargos a diputaciones, para definir a que partido postular\u00e1 en cada uno de los distritos, quedando de la siguiente forma:&nbsp;<\/p>\n\n\n\n<p>En el Distrito 1 en Matehuala por el PT; Distrito 2 en Salinas de Hidalgo por el PVEM; Distrito 3 en Santa Mar\u00eda del Rio por el PVEM; Distrito 4 en San Luis Potos\u00ed por el PT; Distrito 5 en San Luis Potos\u00ed por el PVEM; Distrito 6 en San Luis Potos\u00ed por el PVEM; Distrito 7 en San Luis Potos\u00ed por MORENA; Distrito 9 en Soledad de Graciano S\u00e1nchez por el PVEM; Distrito 10 en Soledad de Graciano S\u00e1nchez por el PT; Distrito 11 en Rioverde por el PT; Distrito 12 en C\u00e1rdenas por MORENA; Distrito 13 en Ciudad Valles&nbsp; por MORENA; Distrito 14 en Tamu\u00edn&nbsp; por el PVEM; y Distrito 15 en Tamazunchale por el PVEM.<\/p>\n\n\n\n<p>En cuanto a la Coalici\u00f3n Fuerza y Coraz\u00f3n por San Luis, no realiz\u00f3 modificaciones en su convenio en el siglado de las diputaciones locales, conform\u00e1ndose de la siguiente forma:<\/p>\n\n\n\n<p>En el Distrito 1 en Matehuala por el PRI; Distrito 2 en Salinas de Hidalgo por el PRI; Distrito 3 en Santa Mar\u00eda del Rio por el PRI; Distrito 4 en San Luis Potos\u00ed por el PAN; Distrito 5 en San Luis Potos\u00ed por el PAN; Distrito 6 en San Luis Potos\u00ed por el PRD; Distrito 7 en San Luis Potos\u00ed por PAN; Distrito 8 en San Luis Potos\u00ed por PAN; Distrito 9 en Soledad de Graciano S\u00e1nchez por el PAN; Distrito 10 en Soledad de Graciano S\u00e1nchez por el PRD; Distrito 11 en Rioverde por el PAN; Distrito 12 en C\u00e1rdenas por PRI; Distrito 13 en Ciudad Valles&nbsp; por PRI; Distrito 14 en Tamu\u00edn&nbsp; por el PRD; y Distrito 15 en Tamazunchale por el PAN.<\/p>\n\n\n\n<p>Cabe se\u00f1alar que el d\u00eda 7 de marzo vence el plazo para realizar cualquier modificaci\u00f3n de los convenios para los cargos de ayuntamientos.<\/p>\n\n\n\n<p>Debe considerarse en las coaliciones el respeto absoluto al principio de paridad en las candidaturas, as\u00ed como la obligaci\u00f3n en la postulaci\u00f3n de personas pertenecientes a los grupos prioritarios, de acuerdo a la normatividad electoral vigente en el estado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Consejo General del Consejo Estatal Electoral y de Participaci\u00f3n Ciudadana (CEEPAC) aprob\u00f3 las modificaciones de los convenios de las coaliciones:\u00a0 \u201cSigamos Haciendo Historia en San Luis Potos\u00ed\u201d, integrada por los partidos pol\u00edticos Morena, del Trabajo (PT ) y Verde Ecologista de M\u00e9xico (PVEM), y la Coalici\u00f3n Fuerza y Coraz\u00f3n por San Luis integrada por [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":323,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[13],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/322"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=322"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/322\/revisions"}],"predecessor-version":[{"id":324,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/322\/revisions\/324"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/323"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=322"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=322"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=322"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}