{"id":33490,"date":"2026-05-04T15:20:00","date_gmt":"2026-05-04T15:20:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=33490"},"modified":"2026-05-05T01:02:38","modified_gmt":"2026-05-05T01:02:38","slug":"estado-celebra-10-anos-del-teatro-polivalente-del-ceart","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2026\/05\/04\/estado-celebra-10-anos-del-teatro-polivalente-del-ceart\/","title":{"rendered":"Estado celebra 10 a\u00f1os del teatro polivalente del CEART"},"content":{"rendered":"\n<ul>\n<li><strong>Habr\u00e1 velada art\u00edstica multidisciplinaria con entrada libre para todo el p\u00fablico<\/strong><\/li>\n<\/ul>\n\n\n\n<p>Siguiendo la instrucci\u00f3n del Gobernador Ricardo Gallardo Cardona para fortalecer el acceso a la cultura y el desarrollo art\u00edstico, la Secretar\u00eda de Cultura, a trav\u00e9s del Centro de las Artes (CEART) San Luis, invita al p\u00fablico en general a celebrar el d\u00e9cimo aniversario del Teatro Polivalente, un espacio emblem\u00e1tico que se ha consolidado como punto de encuentro para las artes esc\u00e9nicas, la m\u00fasica y la creaci\u00f3n contempor\u00e1nea.<\/p>\n\n\n\n<p>La conmemoraci\u00f3n se llevar\u00e1 a cabo el jueves 7 de mayo a las 19:30 horas, con entrada libre, ofreciendo una programaci\u00f3n diversa que refleja el cambio que se vive y se siente en San Luis Potos\u00ed, con una agenda cultural sin l\u00edmites, incluyente y de alta calidad. La velada iniciar\u00e1 con la exposici\u00f3n \u201cDerivas Pict\u00f3ricas\u201d, integrada por obras de alumnas y alumnos del Taller de Producci\u00f3n en Pintura del \u00c1rea Acad\u00e9mica del CEART, seguida de un acto protocolario con la participaci\u00f3n de autoridades culturales.<\/p>\n\n\n\n<p>Como parte del programa esc\u00e9nico, el p\u00fablico disfrutar\u00e1 de la presentaci\u00f3n teatral del grupo Viajeros del Escenario, as\u00ed como de un magno concierto de la Orquesta Sinf\u00f3nica de San Luis Potos\u00ed, dirigida por Enrique Barrios Gonz\u00e1lez. Adem\u00e1s, se presentar\u00e1 un performance con bailarinas y bailarines invitados como Alicia Gerling, Fer LPZ, Mayra Jard\u00f3n, Nina Acu\u00f1a y Pamela Ornelas, para culminar con un Dj Set a cargo de Robert Merch\u00e1n, generando un espacio de convivencia y celebraci\u00f3n art\u00edstica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Siguiendo la instrucci\u00f3n del Gobernador Ricardo Gallardo Cardona para fortalecer el acceso a la cultura y el desarrollo art\u00edstico, la Secretar\u00eda de Cultura, a trav\u00e9s del Centro de las Artes (CEART) San Luis, invita al p\u00fablico en general a celebrar el d\u00e9cimo aniversario del Teatro Polivalente, un espacio emblem\u00e1tico que se ha consolidado como punto [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":33491,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[6],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/33490"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=33490"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/33490\/revisions"}],"predecessor-version":[{"id":33492,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/33490\/revisions\/33492"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/33491"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=33490"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=33490"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=33490"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}