{"id":33513,"date":"2026-05-05T12:40:00","date_gmt":"2026-05-05T12:40:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=33513"},"modified":"2026-05-05T20:26:06","modified_gmt":"2026-05-05T20:26:06","slug":"apoyo-total-a-madres-potosinas-gobernador","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2026\/05\/05\/apoyo-total-a-madres-potosinas-gobernador\/","title":{"rendered":"Apoyo total a madres potosinas: gobernador"},"content":{"rendered":"\n<ul>\n<li><strong>El Gobernador del Estado garantiza el bienestar de las mujeres con las Cl\u00ednicas Rosa, donde se brinda atenci\u00f3n a sus hijas e hijos, as\u00ed como los Cr\u00e9ditos SIFIDE para el emprendimiento, los apoyos alimentarios y las capacitaciones para el trabajo.<\/strong><\/li>\n<\/ul>\n\n\n\n<p>En un ambiente lleno de entusiasmo, cercan\u00eda y respaldo ciudadano, Ricardo Gallardo Cardona, Gobernador de San Luis Potos\u00ed, festej\u00f3, en el marco del 10 de Mayo, a las mam\u00e1s de la capital potosina, donde convivi\u00f3 de manera directa con cientos de ellas, quienes disfrutaron de din\u00e1micas, concursos, m\u00fasica en vivo y m\u00faltiples sorpresas preparadas especialmente para la celebraci\u00f3n.<\/p>\n\n\n\n<p>El Gobernador Ricardo Gallardo entreg\u00f3 diversos regalos a las mam\u00e1s asistentes como muestra de agradecimiento por el papel fundamental que desempe\u00f1an en la construcci\u00f3n de familias y comunidades m\u00e1s fuertes, destacando que, en el cambio que se vive y se siente, su administraci\u00f3n construye un mejor Estado en el que las mujeres cuentan con un Gobierno sensible, incluyente y que camina de su lado.<\/p>\n\n\n\n<p>El Gobernador destac\u00f3 que, m\u00e1s all\u00e1 de este festejo, su administraci\u00f3n mantiene programas concretos para mejorar la calidad de vida de las mujeres y sus familias, entre ellos, \u201cTu Casa, Tu Apoyo\u201d, que otorga terrenos gratuitos y materiales para la construcci\u00f3n de vivienda, beneficiando directamente a madres de familia. Asimismo, resalt\u00f3 la cobertura integral de salud que se brinda a trav\u00e9s de las Cl\u00ednicas Rosas en las cuatro regiones del Estado, donde las mujeres y sus hijas e hijos reciben atenci\u00f3n m\u00e9dica, dental, lentes y estudios sin costo.<\/p>\n\n\n\n<p>A esto se suman programas como la Pensi\u00f3n para Madres Solteras y personas adultas mayores, as\u00ed como la Tarjeta Rosa, que fortalece el acceso a servicios m\u00e9dicos gratuitos en once cl\u00ednicas. En materia econ\u00f3mica, Gallardo Cardona puntualiz\u00f3 que se contin\u00faa impulsando el talento y emprendimiento femenino mediante iniciativas como Expo Mujer Potosina y Expo Mujeres, Oficios y Arte, que brindan capacitaci\u00f3n, apoyos productivos y espacios de comercializaci\u00f3n para madres emprendedoras.<\/p>\n\n\n\n<p>En su mensaje, Ricardo Gallardo reconoci\u00f3 que las madres potosinas son el impulso que no se detiene y reiter\u00f3 que reconocerlas, respaldarlas y visibilizar su esfuerzo es una prioridad permanente de la administraci\u00f3n estatal. \u201cGracias por todo el apoyo; siempre tendr\u00e1n nuestro reconocimiento, no solo el 10 de mayo, ya que son los pilares de sus familias, y siempre contar\u00e1n con el respaldo sin l\u00edmites de este Gobierno\u201d, expres\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En un ambiente lleno de entusiasmo, cercan\u00eda y respaldo ciudadano, Ricardo Gallardo Cardona, Gobernador de San Luis Potos\u00ed, festej\u00f3, en el marco del 10 de Mayo, a las mam\u00e1s de la capital potosina, donde convivi\u00f3 de manera directa con cientos de ellas, quienes disfrutaron de din\u00e1micas, concursos, m\u00fasica en vivo y m\u00faltiples sorpresas preparadas especialmente [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":33514,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[3],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/33513"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=33513"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/33513\/revisions"}],"predecessor-version":[{"id":33515,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/33513\/revisions\/33515"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/33514"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=33513"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=33513"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=33513"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}