{"id":3357,"date":"2024-05-11T13:01:00","date_gmt":"2024-05-11T13:01:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=3357"},"modified":"2024-05-11T21:05:21","modified_gmt":"2024-05-11T21:05:21","slug":"slp-se-queda-con-enrique-galindo-porque-es-ejemplo-de-buen-gobierno-alito-moreno","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2024\/05\/11\/slp-se-queda-con-enrique-galindo-porque-es-ejemplo-de-buen-gobierno-alito-moreno\/","title":{"rendered":"SLP se queda con Enrique Galindo porque es ejemplo de buen gobierno: \u201cAlito\u201d Moreno"},"content":{"rendered":"\n<ul>\n<li><strong>En su visita a la sede estatal del PRI, el presidente del partido a nivel nacional llam\u00f3 al voto por Enrique Galindo para seguir construyendo una mejor ciudad; el candidato a la alcald\u00eda capitalina dijo que debemos sentirnos orgullosos de esta etapa del priismo.<\/strong><\/li>\n<\/ul>\n\n\n\n<p>De gira por San Luis Potos\u00ed, en la sede del Partido Revolucionario Institucional en el estado, el presidente del Comit\u00e9 Ejecutivo Nacional del PRI, Alejandro \u201cAlito\u201d Moreno C\u00e1rdenas, se\u00f1al\u00f3 que en los pr\u00f3ximos comicios, nos estamos jugando el futuro de nuestro pa\u00eds y de San Luis Potos\u00ed: \u201cVamos a marcar la casilla del PRI en las cinco boletas, porque tenemos a los mejores candidatos, desde X\u00f3chitl G\u00e1lvez, los candidatos del senado, las diputaciones federales y locales, y aqu\u00ed en la capital, votemos por el ejemplo del buen gobierno y el crecimiento, para que nos quedemos con Enrique Galindo tres a\u00f1os m\u00e1s para dar resultados\u201d.<\/p>\n\n\n\n<p>Alejandro Moreno C\u00e1rdenas manifest\u00f3 que \u201clas y los priistas, las y los potosinos necesitamos tener muy claro que estamos en un esfuerzo conjunto. Aqu\u00ed est\u00e1 la militancia priista, pero en esta coalici\u00f3n nos acompa\u00f1a el Partido Acci\u00f3n Nacional y el Partido de la Revoluci\u00f3n Democr\u00e1tica, los tres partidos aportamos la fuerza y el compromiso de nuestra gente, de nuestra militancia, para ganar la elecci\u00f3n de este 2 de junio\u201d.<\/p>\n\n\n\n<p>El candidato a la presidencia municipal de San Luis Potos\u00ed, Enrique Galindo Ceballos, agradeci\u00f3 al presidente del PRI Nacional, Alejandro Moreno C\u00e1rdenas, porque su visita al estado fortalece al partido rumbo a las elecciones del pr\u00f3ximo 2 de junio: \u201cNos sentimos muy orgullosos de esta etapa del priismo. Para seguir contribuyendo a construir este M\u00e9xico que queremos, los candidatos del PRI estamos dando la lucha con todo\u201d.<\/p>\n\n\n\n<p>En la sede del PRI abarrotada con cientos de militantes y simpatizantes del tricolor, la dirigente estatal Sara Rocha Medina expres\u00f3 que \u201clos priistas estamos en un partido vivo, unido y listo para ganar, con X\u00f3chitl G\u00e1lvez, con Enrique Galindo y con todos nuestros candidatos y candidatas\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>De gira por San Luis Potos\u00ed, en la sede del Partido Revolucionario Institucional en el estado, el presidente del Comit\u00e9 Ejecutivo Nacional del PRI, Alejandro \u201cAlito\u201d Moreno C\u00e1rdenas, se\u00f1al\u00f3 que en los pr\u00f3ximos comicios, nos estamos jugando el futuro de nuestro pa\u00eds y de San Luis Potos\u00ed: \u201cVamos a marcar la casilla del PRI en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3358,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[7],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/3357"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=3357"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/3357\/revisions"}],"predecessor-version":[{"id":3359,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/3357\/revisions\/3359"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/3358"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=3357"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=3357"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=3357"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}