{"id":33662,"date":"2026-05-07T17:11:00","date_gmt":"2026-05-07T17:11:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=33662"},"modified":"2026-05-08T00:53:13","modified_gmt":"2026-05-08T00:53:13","slug":"san-luis-sera-sede-de-la-cumbre-internacional-nasco-2027","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2026\/05\/07\/san-luis-sera-sede-de-la-cumbre-internacional-nasco-2027\/","title":{"rendered":"San Luis ser\u00e1 sede de la cumbre internacional NASCO 2027"},"content":{"rendered":"\n<ul>\n<li><strong>La entidad fue designada sede de la NASCO Continental Reunion 2027, consolid\u00e1ndose como referente log\u00edstico, industrial y de competitividad en Norteam\u00e9rica.<\/strong><\/li>\n<\/ul>\n\n\n\n<p>Como parte del impulso al desarrollo econ\u00f3mico y la competitividad internacional, San Luis Potos\u00ed fue designado oficialmente como sede de la NASCO Continental Reunion 2027, uno de los encuentros m\u00e1s importantes de log\u00edstica, comercio e infraestructura de Norteam\u00e9rica. En representaci\u00f3n del Gobernador Ricardo Gallardo Cardona, el titular de la Secretar\u00eda de Desarrollo Econ\u00f3mico (Sedeco), Jes\u00fas Salvador Gonz\u00e1lez Mart\u00ednez, recibi\u00f3 esta distinci\u00f3n en Canad\u00e1.<\/p>\n\n\n\n<p>Durante el evento se present\u00f3 un mensaje del Mandatario Estatal, quien destac\u00f3 que San Luis Potos\u00ed es hoy el rostro del cambio y la competitividad en M\u00e9xico, adem\u00e1s de refrendar que la entidad est\u00e1 preparada para recibir a l\u00edderes y directivos de M\u00e9xico, Estados Unidos y Canad\u00e1, fortaleciendo la estrategia de competitividad global del bloque comercial del T-MEC. Este logro proyecta internacionalmente al Estado y reconoce su liderazgo en infraestructura industrial y log\u00edstica.<\/p>\n\n\n\n<p>El cambio que se vive y se siente contin\u00faa posicionando a la entidad entre los mercados m\u00e1s din\u00e1micos del mundo. El titular de la dependencia destac\u00f3 que albergar este encuentro continental permitir\u00e1 mostrar las ventajas competitivas que han convertido al Estado en un polo de atracci\u00f3n para la inversi\u00f3n extranjera, adem\u00e1s de generar beneficios econ\u00f3micos directos para las y los potosinos, consolidando a San Luis Potos\u00ed como un gran anfitri\u00f3n y motor del desarrollo regional.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Como parte del impulso al desarrollo econ\u00f3mico y la competitividad internacional, San Luis Potos\u00ed fue designado oficialmente como sede de la NASCO Continental Reunion 2027, uno de los encuentros m\u00e1s importantes de log\u00edstica, comercio e infraestructura de Norteam\u00e9rica. En representaci\u00f3n del Gobernador Ricardo Gallardo Cardona, el titular de la Secretar\u00eda de Desarrollo Econ\u00f3mico (Sedeco), Jes\u00fas [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":33663,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[3],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/33662"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=33662"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/33662\/revisions"}],"predecessor-version":[{"id":33664,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/33662\/revisions\/33664"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/33663"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=33662"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=33662"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=33662"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}