{"id":33674,"date":"2026-05-08T12:48:00","date_gmt":"2026-05-08T12:48:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=33674"},"modified":"2026-05-08T18:51:01","modified_gmt":"2026-05-08T18:51:01","slug":"villa-de-pozos-fortalece-protocolos-de-atencion-a-mujeres","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2026\/05\/08\/villa-de-pozos-fortalece-protocolos-de-atencion-a-mujeres\/","title":{"rendered":"Villa de Pozos fortalece protocolos de atenci\u00f3n a mujeres"},"content":{"rendered":"\n<ul>\n<li><strong>Personal municipal recibi\u00f3 capacitaci\u00f3n especializada para mejorar la atenci\u00f3n y acompa\u00f1amiento a mujeres.<\/strong><\/li>\n<\/ul>\n\n\n\n<p>La Instancia de la Mujer de Villa de Pozos llev\u00f3 a cabo la capacitaci\u00f3n \u201cProtocolo especializado para la tramitaci\u00f3n y seguimiento de \u00f3rdenes de protecci\u00f3n\u201d, realizada en las instalaciones del CBTA 196, con el objetivo de fortalecer la atenci\u00f3n y actuaci\u00f3n institucional en favor de mujeres en situaci\u00f3n de violencia.<\/p>\n\n\n\n<p>Durante esta jornada de capacitaci\u00f3n, la directora de la Instancia de la Mujer, Nelly L\u00f3pez Soto, inform\u00f3 que personal de la Guardia Civil Municipal, Protecci\u00f3n Civil y DIF Municipal, recibi\u00f3 herramientas y conocimientos enfocados en la correcta aplicaci\u00f3n de protocolos, seguimiento y atenci\u00f3n de casos, para fortalecer la coordinaci\u00f3n interinstitucional y la protecci\u00f3n de los derechos de las mujeres.<\/p>\n\n\n\n<p>Adem\u00e1s, la titular mencion\u00f3 que la actividad cont\u00f3 con la participaci\u00f3n del Centro de Justicia para las Mujeres, a trav\u00e9s de la Lic. Liliana Leticia Gonz\u00e1lez Ochoa y el Lic. Zenaido Antonio Mart\u00ednez Flores, quienes compartieron conocimientos especializados y experiencias relacionadas con la atenci\u00f3n integral y el acompa\u00f1amiento a v\u00edctimas.<\/p>\n\n\n\n<p>Asimismo, se reconoci\u00f3 la disposici\u00f3n del director del CBTA 196 por las facilidades brindadas para la realizaci\u00f3n de esta capacitaci\u00f3n, la cual ayudar\u00e1 en el trabajo coordinado entre instituciones, para impulsar una atenci\u00f3n m\u00e1s humana, profesional y efectiva para las mujeres del municipio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Instancia de la Mujer de Villa de Pozos llev\u00f3 a cabo la capacitaci\u00f3n \u201cProtocolo especializado para la tramitaci\u00f3n y seguimiento de \u00f3rdenes de protecci\u00f3n\u201d, realizada en las instalaciones del CBTA 196, con el objetivo de fortalecer la atenci\u00f3n y actuaci\u00f3n institucional en favor de mujeres en situaci\u00f3n de violencia. Durante esta jornada de capacitaci\u00f3n, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":33675,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/33674"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=33674"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/33674\/revisions"}],"predecessor-version":[{"id":33676,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/33674\/revisions\/33676"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/33675"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=33674"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=33674"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=33674"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}