{"id":33725,"date":"2026-05-09T09:09:00","date_gmt":"2026-05-09T09:09:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=33725"},"modified":"2026-05-10T01:06:44","modified_gmt":"2026-05-10T01:06:44","slug":"gobierno-estatal-avanza-en-la-modernizacion-de-la-carretera-22-en-zaragoza","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2026\/05\/09\/gobierno-estatal-avanza-en-la-modernizacion-de-la-carretera-22-en-zaragoza\/","title":{"rendered":"Gobierno estatal avanza en la modernizaci\u00f3n de la carretera 22 en Zaragoza"},"content":{"rendered":"\n<ul>\n<li><strong>M\u00e1s de 6 kil\u00f3metros de nuevo camino tendr\u00e1n los habitantes de ese municipio.<\/strong><\/li>\n<\/ul>\n\n\n\n<p>Bajo la encomienda del Gobernador Ricardo Gallardo Cardona, el Gobierno del Estado contin\u00faa avanzando en la modernizaci\u00f3n y ampliaci\u00f3n de la carretera 22, que fortalecer\u00e1 la conectividad de Zaragoza hacia el entronque con la carretera Rioverde. Esta obra estrat\u00e9gica representa el cambio que se vive y se siente, al responder a una demanda hist\u00f3rica de m\u00e1s de 30 a\u00f1os de abandono.<\/p>\n\n\n\n<p>Actualmente se realizan trabajos de tendido, nivelaci\u00f3n y compactaci\u00f3n de terracer\u00edas en la zona de ampliaci\u00f3n de la carretera, adem\u00e1s de excavaciones para la construcci\u00f3n de cruces pluviales que permitir\u00e1n una infraestructura m\u00e1s segura y funcional. La parte t\u00e9cnica de los avances y procesos constructivos es supervisada por la titular de la Secretar\u00eda de Desarrollo Urbano, Vivienda y Obras P\u00fablicas (Seduvop), Isabel Leticia Vargas Tinajero, quien destac\u00f3 que la obra avanza conforme a la planeaci\u00f3n establecida para garantizar calidad y durabilidad.<\/p>\n\n\n\n<p>Con esta modernizaci\u00f3n carretera, el Gobierno del Estado refrenda su compromiso de llevar infraestructura de calidad a las cuatro regiones, impulsando un desarrollo sin l\u00edmites que fortalezca la econom\u00eda, mejore la movilidad y acerque m\u00e1s oportunidades para las y los potosinos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bajo la encomienda del Gobernador Ricardo Gallardo Cardona, el Gobierno del Estado contin\u00faa avanzando en la modernizaci\u00f3n y ampliaci\u00f3n de la carretera 22, que fortalecer\u00e1 la conectividad de Zaragoza hacia el entronque con la carretera Rioverde. Esta obra estrat\u00e9gica representa el cambio que se vive y se siente, al responder a una demanda hist\u00f3rica de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":33726,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[3],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/33725"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=33725"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/33725\/revisions"}],"predecessor-version":[{"id":33727,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/33725\/revisions\/33727"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/33726"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=33725"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=33725"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=33725"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}