{"id":33767,"date":"2026-05-10T10:54:00","date_gmt":"2026-05-10T10:54:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=33767"},"modified":"2026-05-11T03:58:47","modified_gmt":"2026-05-11T03:58:47","slug":"gran-festejo-a-madres-potosinas-ofrecen-alcalde-enrique-galindo-y-estela-arriaga","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2026\/05\/10\/gran-festejo-a-madres-potosinas-ofrecen-alcalde-enrique-galindo-y-estela-arriaga\/","title":{"rendered":"Gran festejo a madres potosinas, ofrecen Alcalde Enrique Galindo y Estela Arriaga"},"content":{"rendered":"\n<p>&#8211;&nbsp;<strong>Miles<\/strong><strong>&nbsp;de madre<\/strong><strong>s<\/strong><strong>&nbsp;y sus familias disfrutaron del magno concierto \u201cCelebremos a Mam\u00e1\u201d y recibieron regalos, adem\u00e1s de disfrutar de la 6\u00aa. Feria del Elote en el Parque de Morales.<\/strong><\/p>\n\n\n\n<p>Un festejo lleno de alegr\u00eda, m\u00fasica y regalos ofrecieron este s\u00e1bado el Alcalde Enrique Galindo Ceballos y la Maestra Estela Arriaga M\u00e1rquez, Presidenta del DIF Municipal, a las mam\u00e1s potosinas y a sus familias, quienes adem\u00e1s disfrutaron de la gran cantidad de elotes y sus derivados en la 6\u00aa. Feria del Elote en el Parque de Morales.<\/p>\n\n\n\n<p>En su mensaje, el Presidente Municipal Enrique Galindo Ceballos felicit\u00f3 a todas las madres y reiter\u00f3 que para el Gobierno de la Capital el bienestar de las mam\u00e1s y de sus familias seguir\u00e1 siendo una prioridad.<\/p>\n\n\n\n<p>Mientras las festejadas saboreaban la enorme variedad de productos ofrecidos por m\u00e1s de 100 expositores, como elotes preparados de m\u00faltiples maneras, as\u00ed como esquites, pan y hasta nieve, el Jefe del Gobierno de la Capital entreg\u00f3 pantallas y aparatos electrodom\u00e9sticos que fueron sorteados, pero adem\u00e1s dio instrucciones a la Secretar\u00eda del Bienestar para que les entregaran regalos a todas las mam\u00e1s que se registraron.<\/p>\n\n\n\n<p>Tras la entrega de regalos, dio inicio el magno concierto \u201cCelebremos a Mam\u00e1\u201d, que abri\u00f3 con la presentaci\u00f3n del grupo Pop Royal Tenors, que arranc\u00f3 los aplausos con hermosas canciones interpretadas con un estilo inigualable.<\/p>\n\n\n\n<p>Particip\u00f3 tambi\u00e9n en el concierto la cantante Emma Calo, que tambi\u00e9n fue muy ovacionada; y le sigui\u00f3 el Mariachi Femenil Voces de M\u00e9xico, que con sus alegres canciones volvi\u00f3 a encender el \u00e1nimo, para cerrar el gran espect\u00e1culo musical con M\u00e9xico Lindo y Querido, interpretado al un\u00edsono por los artistas y las mam\u00e1s.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8211;&nbsp;Miles&nbsp;de madres&nbsp;y sus familias disfrutaron del magno concierto \u201cCelebremos a Mam\u00e1\u201d y recibieron regalos, adem\u00e1s de disfrutar de la 6\u00aa. Feria del Elote en el Parque de Morales. Un festejo lleno de alegr\u00eda, m\u00fasica y regalos ofrecieron este s\u00e1bado el Alcalde Enrique Galindo Ceballos y la Maestra Estela Arriaga M\u00e1rquez, Presidenta del DIF Municipal, a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":33776,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[4],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/33767"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=33767"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/33767\/revisions"}],"predecessor-version":[{"id":33777,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/33767\/revisions\/33777"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/33776"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=33767"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=33767"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=33767"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}