{"id":33805,"date":"2026-05-11T14:30:00","date_gmt":"2026-05-11T14:30:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=33805"},"modified":"2026-05-11T20:46:52","modified_gmt":"2026-05-11T20:46:52","slug":"nuestro-centro-reconoce-ambicioso-programa-centro-historico-corazon-de-san-luis-del-gobierno-de-la-capital","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2026\/05\/11\/nuestro-centro-reconoce-ambicioso-programa-centro-historico-corazon-de-san-luis-del-gobierno-de-la-capital\/","title":{"rendered":"Nuestro Centro reconoce ambicioso programa \u201cCentro Hist\u00f3rico, Coraz\u00f3n de San Luis\u201d, del Gobierno de la Capital"},"content":{"rendered":"\n<ul>\n<li><strong>\u201cCon \u2018Centro Hist\u00f3rico, Coraz\u00f3n de San Luis\u2019, esta zona ser\u00e1 tratada como la joya del Estado\u201d: M\u00f3nica Heredia, Presidenta de la Asociaci\u00f3n.<\/strong><\/li>\n\n\n\n<li><strong>Resalta la conjunci\u00f3n de esfuerzos entre distintas direcciones del Gobierno de la Capital.<\/strong><\/li>\n<\/ul>\n\n\n\n<p>La Presidenta de la asociaci\u00f3n \u201cNuestro Centro\u201d, M\u00f3nica Heredia S\u00e1inz, calific\u00f3 como \u201cun proyecto muy ambicioso\u201d el nuevo programa municipal denominado: \u201cCentro Hist\u00f3rico, Coraz\u00f3n de San Luis\u201d, para que esta zona de la Capital potosina, \u201csea tratada como la joya que es de todo el Estado\u201d.<\/p>\n\n\n\n<p>M\u00f3nica Heredia, tambi\u00e9n Presidenta del Consejo de Seguridad del Centro Hist\u00f3rico, resalt\u00f3 que con esta estrategia impulsada por el Alcalde, Enrique Galindo Ceballos, se busca rescatar, pero tambi\u00e9n mejorar el primer cuadro de la ciudad, para hacerlo \u201cmucho m\u00e1s amable\u201d.<\/p>\n\n\n\n<p>\u201cTenemos grandes expectativas en este proyecto en el cual participar\u00e1n distintas direcciones municipales, a quienes agradecemos su involucramiento a trav\u00e9s de diversas acciones en diferentes espacios\u201d, a\u00f1adi\u00f3 Heredia Sainz.<\/p>\n\n\n\n<p>Para concluir, la titular de \u201cNuestro Centro\u201d resalt\u00f3 la disposici\u00f3n tanto del Presidente Municipal, Enrique Galindo, as\u00ed como del Gobierno de la Capital en general, \u201cpor tener siempre presente este cuadrante tan importante de nuestra ciudad\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Presidenta de la asociaci\u00f3n \u201cNuestro Centro\u201d, M\u00f3nica Heredia S\u00e1inz, calific\u00f3 como \u201cun proyecto muy ambicioso\u201d el nuevo programa municipal denominado: \u201cCentro Hist\u00f3rico, Coraz\u00f3n de San Luis\u201d, para que esta zona de la Capital potosina, \u201csea tratada como la joya que es de todo el Estado\u201d. M\u00f3nica Heredia, tambi\u00e9n Presidenta del Consejo de Seguridad del [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":33806,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[4],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/33805"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=33805"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/33805\/revisions"}],"predecessor-version":[{"id":33807,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/33805\/revisions\/33807"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/33806"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=33805"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=33805"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=33805"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}