{"id":33851,"date":"2026-05-12T12:05:00","date_gmt":"2026-05-12T12:05:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=33851"},"modified":"2026-05-12T19:26:12","modified_gmt":"2026-05-12T19:26:12","slug":"facultad-de-medicina-de-la-uaslp-impulsa-actualizacion-medica-ante-creciente-incidencia-de-enfermedad-renal-cronica","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2026\/05\/12\/facultad-de-medicina-de-la-uaslp-impulsa-actualizacion-medica-ante-creciente-incidencia-de-enfermedad-renal-cronica\/","title":{"rendered":"Facultad de Medicina de la UASLP impulsa actualizaci\u00f3n m\u00e9dica ante creciente incidencia de enfermedad renal cr\u00f3nica"},"content":{"rendered":"\n<p>Ante el incremento de casos de enfermedad renal cr\u00f3nica y la necesidad de fortalecer la detecci\u00f3n oportuna y el tratamiento especializado de este padecimiento, la Facultad de Medicina de la Universidad Aut\u00f3noma de San Luis Potos\u00ed (UASLP) realizar\u00e1 los d\u00edas 22 y 23 de mayo el XVII Curso de Actualizaci\u00f3n en Nefrolog\u00eda. Este encuentro acad\u00e9mico reunir\u00e1 a especialistas nacionales e internacionales para abordar los avances m\u00e1s recientes en diagn\u00f3stico, tratamiento y prevenci\u00f3n de enfermedades renales. El doctor Alejandro Chevaile Ramos, coordinador de la Especialidad en Nefrolog\u00eda, destac\u00f3 que el evento contar\u00e1 con modalidad h\u00edbrida y estar\u00e1 abierto a m\u00e9dicos, estudiantes y profesionales de distintas \u00e1reas de la salud.<\/p>\n\n\n\n<p>La enfermedad renal cr\u00f3nica representa actualmente uno de los principales retos de salud p\u00fablica a nivel mundial al afectar aproximadamente al 10 por ciento de la poblaci\u00f3n, \u201cnuestro pa\u00eds no es la excepci\u00f3n. Tiene tanta relevancia que uno de los protocolos nacionales de atenci\u00f3n m\u00e9dica est\u00e1 dirigido a la enfermedad renal cr\u00f3nica\u201d, se\u00f1al\u00f3. A\u00f1adi\u00f3 que el curso revisar\u00e1 estrategias para el diagn\u00f3stico oportuno y el control de factores de riesgo como diabetes, hipertensi\u00f3n y obesidad, padecimientos estrechamente relacionados con el deterioro de la funci\u00f3n renal.<\/p>\n\n\n\n<p>Durante las jornadas se abordar\u00e1n temas como nutrici\u00f3n renal, tratamientos de vanguardia, hemodi\u00e1lisis, enfermedades glomerulares, trasplante renal y nefrolog\u00eda verde, una l\u00ednea que busca reducir el impacto ambiental de los tratamientos m\u00e9dicos. \u201cHay un poco para todo mundo\u201d, coment\u00f3 el doctor Chevaile Ramos al referirse a la diversidad de contenidos dirigidos a m\u00e9dicos generales, internistas, endocrin\u00f3logos, nefr\u00f3logos, personal de enfermer\u00eda, qu\u00edmicos, nutri\u00f3logos y estudiantes de diversas carreras relacionadas con la salud.<\/p>\n\n\n\n<p>El coordinador subray\u00f3 la importancia de la detecci\u00f3n temprana, ya que en muchos casos la enfermedad renal avanza sin s\u00edntomas visibles. \u201cLos ri\u00f1ones no duelen en estas enfermedades y ya cuando empiezas a notar que se te hinchan los pies o que tu orina hace mucha espuma, generalmente es un estadio muy tard\u00edo\u201d, explic\u00f3. Agreg\u00f3 que estudios sencillos como un examen general de orina, la medici\u00f3n de creatinina en sangre y de alb\u00famina urinaria permiten detectar el problema en etapas iniciales y comenzar tratamientos que ayuden a modificar el curso de la enfermedad.<\/p>\n\n\n\n<p>Asimismo, advirti\u00f3 que una gran cantidad de pacientes desconoce que padece da\u00f1o renal. \u201cCuando hemos hecho campa\u00f1as de tamizaje temprano encontramos que la tercera parte de los pacientes diab\u00e9ticos o hipertensos ya ten\u00edan enfermedad renal cr\u00f3nica que no se hab\u00eda diagnosticado previamente\u201d, indic\u00f3. Precis\u00f3 que, en personas con diabetes e hipertensi\u00f3n simult\u00e1neamente, el porcentaje puede elevarse hasta la mitad de los casos, lo que refuerza la necesidad de revisiones m\u00e9dicas peri\u00f3dicas.<\/p>\n\n\n\n<p>Finalmente, el doctor Chevaile Ramos resalt\u00f3 el respaldo de la UASLP y de las instituciones participantes para hacer posible este encuentro acad\u00e9mico con cuotas accesibles. \u201cLa ciencia no se detiene y este curso se ha convertido en uno de los eventos que cada a\u00f1o realizamos con mucho gusto y compromiso\u201d, expres\u00f3.<\/p>\n\n\n\n<p>El programa contar\u00e1 con especialistas pertenecientes al Sistema Nacional de Investigadores y representantes de instituciones como el Instituto Nacional de Ciencias M\u00e9dicas y Nutrici\u00f3n Salvador Zubir\u00e1n, el IMSS, el Instituto Nacional de Cancerolog\u00eda y la Universidad de Kansas, en Estados Unidos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ante el incremento de casos de enfermedad renal cr\u00f3nica y la necesidad de fortalecer la detecci\u00f3n oportuna y el tratamiento especializado de este padecimiento, la Facultad de Medicina de la Universidad Aut\u00f3noma de San Luis Potos\u00ed (UASLP) realizar\u00e1 los d\u00edas 22 y 23 de mayo el XVII Curso de Actualizaci\u00f3n en Nefrolog\u00eda. Este encuentro acad\u00e9mico [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":33852,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[8],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/33851"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=33851"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/33851\/revisions"}],"predecessor-version":[{"id":33853,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/33851\/revisions\/33853"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/33852"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=33851"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=33851"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=33851"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}